{"id":291427,"date":"2023-10-13T12:00:58","date_gmt":"2023-10-13T10:00:58","guid":{"rendered":"https:\/\/www.katia.com\/blog\/it\/?p=6175"},"modified":"2024-03-12T09:11:56","modified_gmt":"2024-03-12T08:11:56","slug":"come-realizzare-un-costume-da-polpo-per-halloween","status":"publish","type":"post","link":"https:\/\/www.katia.com\/blog\/it\/come-realizzare-un-costume-da-polpo-per-halloween\/","title":{"rendered":"Come realizzare un costume da polpo per Halloween \ud83d\udc19"},"content":{"rendered":"<p>Questo Halloween sorprendi tutti con un <strong>costume da polipo <\/strong>realizzato da te. In questo nuovo video tutorial condividiamo le istruzioni passo dopo passo per imparare <strong>a realizzare un costume da polpo<\/strong>. Scopri nel video come Ana di\u00a0<a href=\"https:\/\/www.instagram.com\/nanitatelier\/\" target=\"_blank\" rel=\"noopener\">@nanitatelier<\/a>\u00a0trasforma un\u00a0<a href=\"https:\/\/www.katia.com\/IT\/Design-felpa-con-cappuccio-da-donna-W22-5015.html\" target=\"_blank\" rel=\"noopener\">modello di cucito per una felpa<\/a>\u00a0in un sorprendente costume da polpo. Divertiti a creare i tuoi costumi per la notte pi\u00f9 paurosa e dolce dell\u2019anno!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6179 size-full\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/it\/wp-content\/uploads\/2023\/10\/Octopus-Costume.jpg?resize=640%2C640&#038;ssl=1\" alt=\"a realizzare un costume da polpo\" width=\"640\" height=\"640\" data-recalc-dims=\"1\" \/><\/p>\n<p>Per insegnarti a cucire il tuo costume abbiamo invitato <a href=\"https:\/\/www.instagram.com\/nanitatelier\/\" target=\"_blank\" rel=\"noopener\">@nanitatelier<\/a>, una appassionata del cucito che ci mostrer\u00e0 come realizzare la felpa con tutti i dettagli e come modificarla per trasformarla in una felpa con tentacoli e testa da polpo.<\/p>\n<p style=\"padding-left: 40px;\">Sono Ana! La ragazza proprietaria dell\u2019account <a href=\"https:\/\/www.instagram.com\/nanitatelier\/\" target=\"_blank\" rel=\"noopener\">@nanitatelier<\/a>\u00a0e in ogni foto. Ho imparato a cucire da tempo\u2026 Per\u00f2 mi sono lanciata sui capi nel 2020, quando mi sono riproposta di cucire il mio guardaroba completo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6178 size-full\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/it\/wp-content\/uploads\/2023\/10\/Disfraz-pulpo.jpg?resize=1020%2C266&#038;ssl=1\" alt=\"a realizzare un costume da polpo\" width=\"1020\" height=\"266\" data-recalc-dims=\"1\" \/><\/p>\n<h2>Tessuti di Halloween<\/h2>\n<p>Per realizzare questo modello Halloween utilizza il nostro tessuto <a href=\"https:\/\/www.katia.com\/IT\/fabric-tessuto-con-mini-bloucle-curled-cotton-celestial-blue-2079-8.html?color=1-Rust\" target=\"_blank\" rel=\"noopener\"><strong>Curled Cotton<\/strong><\/a>\u00a0per la\u00a0<strong>felpa<\/strong>\u00a0e\u00a0<a href=\"https:\/\/www.katia.com\/IT\/fabric-js12-jersey-solid-colors-rust-2117-12.html?color=9-Make-up-Pink\" target=\"_blank\" rel=\"noopener\"><strong>tessuto jersey<\/strong><\/a>\u00a0per la parte interna dei <strong>tentacoli. <\/strong>Entrambi sono ideali per realizzare questo tipo di progetti grazie alla loro elasticit\u00e0.<\/p>\n<p>In oltre, se cerchi altri <a href=\"https:\/\/www.katia.com\/IT\/tessuti.html?promo[]=NEW\" target=\"_blank\" rel=\"noopener\"><strong>tessuti per Halloween<\/strong><\/a>, dai uno sguardo alla <strong>collezione di tessuti con stampe divertenti<\/strong> e <strong>spaventose <\/strong>per liberare la tua creativit\u00e0 in questa festa dell\u2019orrore. Sicuramente il tuo costume sar\u00e0 il pi\u00f9 originale!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/www.katia.com\/files\/telas\/2172\/tejido-de-viscosa-ecoviscose-cats-moon-2172-26-02-katia-n.jpg?resize=600%2C600&#038;ssl=1\" alt=\"\" width=\"600\" height=\"600\" data-recalc-dims=\"1\" \/><\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/www.katia.com\/files\/telas\/2101\/tela-popelin-de-algodon-poplin-halloween-potions-2101-184-01-katia-n.jpg?w=1020&#038;ssl=1\" data-recalc-dims=\"1\" \/><\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/www.katia.com\/files\/telas\/2143\/tejido-de-coralina-coraline-print-halloween-bats-2143-3-01-katia-n.jpg?w=1020&#038;ssl=1\" data-recalc-dims=\"1\" \/><\/p>\n<h2>Come cucire un costume da polpo passo dopo passo<\/h2>\n<p>Di seguito ti indichiamo i <strong>materiali <\/strong>e gli <strong>accessori <\/strong>necessari, cos\u00ec come alcuni <strong>consigli <\/strong>per una buona confezione.<\/p>\n<h3>Materiale:<\/h3>\n<ul>\n<li>Modello Felpa donna (S-XL) in\u00a0<a href=\"https:\/\/www.katia.com\/IT\/Design-felpa-con-cappuccio-da-donna-W22-5015.html\" target=\"_blank\" rel=\"noopener\">PDF<\/a><\/li>\n<li>1.5 m di tessuto: <a href=\"https:\/\/www.katia.com\/IT\/fabric-tessuto-con-mini-bloucle-curled-cotton-celestial-blue-2079-8.html?color=1-Rust\" target=\"_blank\" rel=\"noopener\">Curled Cotton<\/a> come tessuto esterno.<\/li>\n<li>50 cm di tessuto:<a href=\"https:\/\/www.katia.com\/IT\/fabric-js12-jersey-solid-colors-rust-2117-12.html?color=9-Make-up-Pink\" target=\"_blank\" rel=\"noopener\"> Jersey Make-up Pink<\/a> per i tentacoli e la fodera della testa del polpo<\/li>\n<\/ul>\n<h3>Accessori:<\/h3>\n<ul>\n<li>Forbici<\/li>\n<li>Spilli<\/li>\n<li>Forbici per carta<\/li>\n<li>Nastro per misurare<\/li>\n<li>Pennarello<\/li>\n<li>Tagliafili<\/li>\n<li>Ferro da stiro<\/li>\n<li>Macchina da cucire<\/li>\n<\/ul>\n<h3>Consigli:<\/h3>\n<ul>\n<li>\u00c9 importante che i tessuti siano <strong>lavati<\/strong>e stirati prima di cominciare ad utilizzarli.<\/li>\n<li>Tutte le parti del modello hanno gi\u00e0 le cuciture di 1 cm incluse, a meno che sia indicato diversamente.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6177 size-full\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/it\/wp-content\/uploads\/2023\/10\/Disfraz-facil-pulpo.jpg?resize=550%2C850&#038;ssl=1\" alt=\"a realizzare un costume da polpo\" width=\"550\" height=\"850\" data-recalc-dims=\"1\" \/><\/p>\n<h3>Modifiche al modello della felpa<\/h3>\n<p>La prima cosa che devi fare \u00e8 <a href=\"https:\/\/www.katia.com\/IT\/Design-felpa-con-cappuccio-da-donna-W22-5015.html\" target=\"_blank\" rel=\"noopener\">scaricare e\u00a0<strong>assemblare il modello<\/strong>\u00a0in PDF<\/a>. Leggi attentamente tutte le <strong>istruzioni<\/strong>.<\/p>\n<p>Poi devi <strong>tagliare i modelli<\/strong> di carta. Per fare questo, ti lasciamo questo post in cui vedrai <a href=\"https:\/\/www.katia.com\/blog\/es\/como-calcar-y-copiar-los-patrones-de-costura-katia-fabric\/\" target=\"_blank\" rel=\"noopener\"><strong>Come disegnare e tagliare <\/strong>i cartamodelli <\/a>\u00a0nel caso ti sia utile. Una volta che hai tagliato i pezzi con le tacche e i segni corrispondenti, passa alla <strong>confezione<\/strong>.<\/p>\n<p>Devi apportare tre <strong>modifiche al modello<\/strong> di cucito:<\/p>\n<ol>\n<li>Cappello per realizzare la testa.<\/li>\n<li>Aumentare la lunghezza del modello.<\/li>\n<li>Creare i tentacoli.<\/li>\n<\/ol>\n<p>Infine, devi avere le seguenti <strong>parti del modello<\/strong>:<\/p>\n<ul>\n<li>1 davanti tagliato sul tessuto principale<\/li>\n<li>Una parte posteriore tagliata sul tessuto principale<\/li>\n<li>Cappuccio modificato. 2 parti sul tessuto principale e due sul tessuto della fodera<\/li>\n<li>2 maniche sul tessuto principale<\/li>\n<li>8 tentacoli. Devi averne 8 sul tessuto principale e 8 sulla fodera<\/li>\n<\/ul>\n<p><strong>Passo dopo passo per confezionare il costume da polpo <\/strong><\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"1020\" height=\"574\" src=\"https:\/\/www.youtube.com\/embed\/5LtKTef2TQo?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=it-IT&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n<h3>Come cucire la felpa<\/h3>\n<ol>\n<li>Per cominciare a <strong>cucire la felpa<\/strong>, sistema il diritto del davanti sul diritto del dietro. Cuci le spalle, con una cucitura diritta a 1 cm.<\/li>\n<li>Unisci le maniche, facendo coincidere il centro delle maniche alle spalle, sistema il diritto della manica sul corpo e cuci a 1 cm.<\/li>\n<li>Poi, chiudi i lati con una cucitura diritta a 1 cm.<\/li>\n<li>Fai gli orli delle maniche e inserisci gli elastici perch\u00e8 la manica sia chiusa.<\/li>\n<\/ol>\n<h3>Come cucire la testa del polpo<\/h3>\n<ol>\n<li>Per cucire il cappuccio, quella che sar\u00e0 la testa del polpo, sistema le parti della fodera una di fronte all\u2019altra e cuci lungo la parte curva a 1 cm. Ripeti la stessa operazione con il tessuto principale.<\/li>\n<li>\u00c9 il momento di collocare gli occhi sulla parte superiore del cappuccio sul tessuto principale.<\/li>\n<li>Sistema il diritto di entrambi i cappucci uno davanti all\u2019altro e cuci unendoli sulla parte anteriore.<\/li>\n<li>Risvolta e stira per fissare il davanti. Fai una cucitura a circa 5 mm dal bordo per fissare il cappuccio.<\/li>\n<li>Inserisci l\u2019imbottitura all\u2019interno per dare forma alla testa del polpo.<\/li>\n<li>Unisci il cappuccio al corpo, cucendolo tutto attorno allo scollo, diritto contro diritto, sovrapponendo l\u2019incrocio del cappuccio, seguendo le parti marcate del modello.<\/li>\n<\/ol>\n<h3>Cuci i tentacoli<\/h3>\n<ol>\n<li>Per i tentacoli, unisci una parte del tessuto principale a una della fodera, diritto contro diritto e cuci a 1 cm. Risvolta sul diritto i tentacoli e inserisci l\u2019imbottitura.<\/li>\n<li>Fai l\u2019orlo della felpa e cuci i tentacoli all\u2019orlo.<\/li>\n<li>Come decorazione, puoi dipingere un cerchio con vernice per tessuti sulla parte della fodera imitando le ventose.<\/li>\n<li>Pronto! Ecco il tuo polpo Paul.<\/li>\n<\/ol>\n<p>Ci auguriamo che lo realizzerai e che ci mostrerai la tua versione utilizzando l\u2019hashtag #katiafabrics.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6176 size-full\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/it\/wp-content\/uploads\/2023\/10\/Como-hacer-un-disfraz-de-pulpo-para-Halloween.jpg?resize=550%2C850&#038;ssl=1\" alt=\"a realizzare un costume da polpo\" width=\"550\" height=\"850\" data-recalc-dims=\"1\" \/><\/p>\n<p>Se cerchi pi\u00f9\u00a0<strong>progetti per Halloween,\u00a0<\/strong>potrebbero anche interessarti:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.katia.com\/blog\/es\/tutorial-de-halloween-calabazas-y-fantasmas-de-tela\/\" target=\"_blank\" rel=\"noopener\">Tutorial di Halloween: Decora la tua casa con zucche<u> e fantasmi di stoffa<\/u><\/a><\/li>\n<li><a href=\"https:\/\/www.katia.com\/blog\/it\/copri-tazza-alluncinetto-halloween\/\" target=\"_blank\" rel=\"noopener\">4 copri tazza all\u2019uncinetto di Lalala Toys: Questo Halloween brinda con Dracula, Calabaza, Momia e Frankenstein<\/a><\/li>\n<li><a href=\"https:\/\/www.katia.com\/blog\/it\/modelli-di-halloween-piccoli-mostri\/\" target=\"_blank\" rel=\"noopener\">6 modelli di Halloween per<u> i tuoi piccoli mostriciattoli<\/u><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Questo Halloween sorprendi tutti con un costume da polipo realizzato da te. In questo nuovo video tutorial condividiamo le istruzioni passo dopo passo per imparare a realizzare un costume da polpo. Scopri nel video come Ana di\u00a0@nanitatelier\u00a0trasforma un\u00a0modello di cucito per una felpa\u00a0in un sorprendente costume da polpo. Divertiti a creare i tuoi costumi per&hellip;<\/p>\n","protected":false},"author":6,"featured_media":291428,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[12951,1,11909,12002,12022,12008,12011,12014,12021],"tags":[4292,10768,11441,11612,11651],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Come realizzare un costume da polpo per Halloween \ud83d\udc19<\/title>\n<meta name=\"description\" content=\"Scopri nel video come Ana di\u00a0@nanitatelier\u00a0trasforma un\u00a0modello di cucito per una felpa\u00a0in un sorprendente costume da polpo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.katia.com\/blog\/it\/come-realizzare-un-costume-da-polpo-per-halloween\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come realizzare un costume da polpo per Halloween \ud83d\udc19\" \/>\n<meta property=\"og:description\" content=\"Scopri nel video come Ana di\u00a0@nanitatelier\u00a0trasforma un\u00a0modello di cucito per una felpa\u00a0in un sorprendente costume da polpo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.katia.com\/blog\/it\/come-realizzare-un-costume-da-polpo-per-halloween\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog di cucito, uncinetto e lavoro a maglia | Blog di Katia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KatiaYarns\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-13T10:00:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-12T08:11:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2023\/10\/Octopus-Costume.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jenifer Guti\u00e9rrez | Katia Fabrics Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@katiayarns\" \/>\n<meta name=\"twitter:site\" content=\"@katiayarns\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jenifer Guti\u00e9rrez | Katia Fabrics Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/come-realizzare-un-costume-da-polpo-per-halloween\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/come-realizzare-un-costume-da-polpo-per-halloween\/\"},\"author\":{\"name\":\"Jenifer Guti\u00e9rrez | Katia Fabrics Team\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#\/schema\/person\/465f40fa8b2d52eedab1f09e92cec8ae\"},\"headline\":\"Come realizzare un costume da polpo per Halloween \ud83d\udc19\",\"datePublished\":\"2023-10-13T10:00:58+00:00\",\"dateModified\":\"2024-03-12T08:11:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/come-realizzare-un-costume-da-polpo-per-halloween\/\"},\"wordCount\":811,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#organization\"},\"keywords\":[\"jersey\",\"costumi\",\"felpa\",\"tessuto\",\"modelli di cucito\"],\"articleSection\":{\"1\":\"Sin categorizar\",\"2\":\"Craft Lovers\",\"3\":\"Katia 100% You\",\"4\":\"Fai-da-te per le occasioni speciali\",\"5\":\"Fabrics Lovers\",\"6\":\"Tutorial e Modelli\",\"7\":\"Cucito\",\"8\":\"Idee Fai-da-te\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.katia.com\/blog\/it\/come-realizzare-un-costume-da-polpo-per-halloween\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/come-realizzare-un-costume-da-polpo-per-halloween\/\",\"url\":\"https:\/\/www.katia.com\/blog\/it\/come-realizzare-un-costume-da-polpo-per-halloween\/\",\"name\":\"Come realizzare un costume da polpo per Halloween \ud83d\udc19\",\"isPartOf\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#website\"},\"datePublished\":\"2023-10-13T10:00:58+00:00\",\"dateModified\":\"2024-03-12T08:11:56+00:00\",\"description\":\"Scopri nel video come Ana di\u00a0@nanitatelier\u00a0trasforma un\u00a0modello di cucito per una felpa\u00a0in un sorprendente costume da polpo.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/come-realizzare-un-costume-da-polpo-per-halloween\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.katia.com\/blog\/it\/come-realizzare-un-costume-da-polpo-per-halloween\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/come-realizzare-un-costume-da-polpo-per-halloween\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/www.katia.com\/blog\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come realizzare un costume da polpo per Halloween \ud83d\udc19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#website\",\"url\":\"https:\/\/www.katia.com\/blog\/it\/\",\"name\":\"www.katia.com\",\"description\":\"Tu blog de crochet, punto, costura o macram\u00e9 con tutoriales para aprender e ideas para tejer y coser piezas \u00fanicas. Blog de Katia, para esp\u00edritus creativos.\",\"publisher\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.katia.com\/blog\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#organization\",\"name\":\"Fil Katia, S.A\",\"url\":\"https:\/\/www.katia.com\/blog\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg\",\"contentUrl\":\"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg\",\"width\":\"600\",\"height\":\"1200\",\"caption\":\"Fil Katia, S.A\"},\"image\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/KatiaYarns\/\",\"https:\/\/twitter.com\/katiayarns\",\"http:\/\/instagram.com\/katiayarns\",\"https:\/\/www.linkedin.com\/company\/fil-katia\/\",\"https:\/\/www.pinterest.com\/KatiaYarns\/\",\"https:\/\/www.youtube.com\/c\/KatiaYarnsFabrics\/videos\",\"https:\/\/www.tiktok.com\/@katiacrafts\",\"https:\/\/www.instagram.com\/katiafabrics\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#\/schema\/person\/465f40fa8b2d52eedab1f09e92cec8ae\",\"name\":\"Jenifer Guti\u00e9rrez | Katia Fabrics Team\",\"description\":\"Discover Katia Fabrics, your source of inspiration for creative sewing. Since 2018, we have been creating an exclusive line of fabrics with modern prints and cutting-edge patterns for sewing enthusiasts.\",\"url\":\"https:\/\/www.katia.com\/blog\/it\/author\/katia-fabrics\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come realizzare un costume da polpo per Halloween \ud83d\udc19","description":"Scopri nel video come Ana di\u00a0@nanitatelier\u00a0trasforma un\u00a0modello di cucito per una felpa\u00a0in un sorprendente costume da polpo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.katia.com\/blog\/it\/come-realizzare-un-costume-da-polpo-per-halloween\/","og_locale":"it_IT","og_type":"article","og_title":"Come realizzare un costume da polpo per Halloween \ud83d\udc19","og_description":"Scopri nel video come Ana di\u00a0@nanitatelier\u00a0trasforma un\u00a0modello di cucito per una felpa\u00a0in un sorprendente costume da polpo.","og_url":"https:\/\/www.katia.com\/blog\/it\/come-realizzare-un-costume-da-polpo-per-halloween\/","og_site_name":"Blog di cucito, uncinetto e lavoro a maglia | Blog di Katia","article_publisher":"https:\/\/www.facebook.com\/KatiaYarns\/","article_published_time":"2023-10-13T10:00:58+00:00","article_modified_time":"2024-03-12T08:11:56+00:00","og_image":[{"width":640,"height":640,"url":"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2023\/10\/Octopus-Costume.jpg","type":"image\/jpeg"}],"author":"Jenifer Guti\u00e9rrez | Katia Fabrics Team","twitter_card":"summary_large_image","twitter_creator":"@katiayarns","twitter_site":"@katiayarns","twitter_misc":{"Scritto da":"Jenifer Guti\u00e9rrez | Katia Fabrics Team","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.katia.com\/blog\/it\/come-realizzare-un-costume-da-polpo-per-halloween\/#article","isPartOf":{"@id":"https:\/\/www.katia.com\/blog\/it\/come-realizzare-un-costume-da-polpo-per-halloween\/"},"author":{"name":"Jenifer Guti\u00e9rrez | Katia Fabrics Team","@id":"https:\/\/www.katia.com\/blog\/it\/#\/schema\/person\/465f40fa8b2d52eedab1f09e92cec8ae"},"headline":"Come realizzare un costume da polpo per Halloween \ud83d\udc19","datePublished":"2023-10-13T10:00:58+00:00","dateModified":"2024-03-12T08:11:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.katia.com\/blog\/it\/come-realizzare-un-costume-da-polpo-per-halloween\/"},"wordCount":811,"commentCount":0,"publisher":{"@id":"https:\/\/www.katia.com\/blog\/it\/#organization"},"keywords":["jersey","costumi","felpa","tessuto","modelli di cucito"],"articleSection":{"1":"Sin categorizar","2":"Craft Lovers","3":"Katia 100% You","4":"Fai-da-te per le occasioni speciali","5":"Fabrics Lovers","6":"Tutorial e Modelli","7":"Cucito","8":"Idee Fai-da-te"},"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.katia.com\/blog\/it\/come-realizzare-un-costume-da-polpo-per-halloween\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.katia.com\/blog\/it\/come-realizzare-un-costume-da-polpo-per-halloween\/","url":"https:\/\/www.katia.com\/blog\/it\/come-realizzare-un-costume-da-polpo-per-halloween\/","name":"Come realizzare un costume da polpo per Halloween \ud83d\udc19","isPartOf":{"@id":"https:\/\/www.katia.com\/blog\/it\/#website"},"datePublished":"2023-10-13T10:00:58+00:00","dateModified":"2024-03-12T08:11:56+00:00","description":"Scopri nel video come Ana di\u00a0@nanitatelier\u00a0trasforma un\u00a0modello di cucito per una felpa\u00a0in un sorprendente costume da polpo.","breadcrumb":{"@id":"https:\/\/www.katia.com\/blog\/it\/come-realizzare-un-costume-da-polpo-per-halloween\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.katia.com\/blog\/it\/come-realizzare-un-costume-da-polpo-per-halloween\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.katia.com\/blog\/it\/come-realizzare-un-costume-da-polpo-per-halloween\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.katia.com\/blog\/it\/"},{"@type":"ListItem","position":2,"name":"Come realizzare un costume da polpo per Halloween \ud83d\udc19"}]},{"@type":"WebSite","@id":"https:\/\/www.katia.com\/blog\/it\/#website","url":"https:\/\/www.katia.com\/blog\/it\/","name":"www.katia.com","description":"Tu blog de crochet, punto, costura o macram\u00e9 con tutoriales para aprender e ideas para tejer y coser piezas \u00fanicas. Blog de Katia, para esp\u00edritus creativos.","publisher":{"@id":"https:\/\/www.katia.com\/blog\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.katia.com\/blog\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.katia.com\/blog\/it\/#organization","name":"Fil Katia, S.A","url":"https:\/\/www.katia.com\/blog\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.katia.com\/blog\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg","contentUrl":"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg","width":"600","height":"1200","caption":"Fil Katia, S.A"},"image":{"@id":"https:\/\/www.katia.com\/blog\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KatiaYarns\/","https:\/\/twitter.com\/katiayarns","http:\/\/instagram.com\/katiayarns","https:\/\/www.linkedin.com\/company\/fil-katia\/","https:\/\/www.pinterest.com\/KatiaYarns\/","https:\/\/www.youtube.com\/c\/KatiaYarnsFabrics\/videos","https:\/\/www.tiktok.com\/@katiacrafts","https:\/\/www.instagram.com\/katiafabrics"]},{"@type":"Person","@id":"https:\/\/www.katia.com\/blog\/it\/#\/schema\/person\/465f40fa8b2d52eedab1f09e92cec8ae","name":"Jenifer Guti\u00e9rrez | Katia Fabrics Team","description":"Discover Katia Fabrics, your source of inspiration for creative sewing. Since 2018, we have been creating an exclusive line of fabrics with modern prints and cutting-edge patterns for sewing enthusiasts.","url":"https:\/\/www.katia.com\/blog\/it\/author\/katia-fabrics\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.katia.com\/blog\/wp-content\/uploads\/2023\/10\/Octopus-Costume.jpg?fit=640%2C640&ssl=1","jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/peUVQy-1dOr","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/posts\/291427"}],"collection":[{"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/comments?post=291427"}],"version-history":[{"count":3,"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/posts\/291427\/revisions"}],"predecessor-version":[{"id":299017,"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/posts\/291427\/revisions\/299017"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/media\/291428"}],"wp:attachment":[{"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/media?parent=291427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/categories?post=291427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/tags?post=291427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}