{"id":264041,"date":"2023-03-03T07:00:03","date_gmt":"2023-03-03T06:00:03","guid":{"rendered":"https:\/\/www.katia.com\/blog\/come-cucire-una-coperta-granny-tutorial-facile\/"},"modified":"2023-06-14T11:33:47","modified_gmt":"2023-06-14T09:33:47","slug":"come-cucire-una-coperta-granny-tutorial-facile","status":"publish","type":"post","link":"https:\/\/www.katia.com\/blog\/it\/come-cucire-una-coperta-granny-tutorial-facile\/","title":{"rendered":"Come cucire una coperta stile Granny? \u00c8 facile come seguire il passo dopo passo gratuito di @looksanddiy"},"content":{"rendered":"<p>Cosa ti viene in mente quando pensi a \u201cdivano, coperta e film?\u201d Se la risposta \u00e8 \u201crelax!\u201d Questo post \u00e8 per te. Oggi ti proponiamo <strong>come cucire una coperta <\/strong><em>stile Granny <\/em>cos\u00ec tanto di moda. Grazie al modello passo dopo passo che ha creato Esther di <a href=\"https:\/\/www.instagram.com\/looksanddiy\/\" target=\"_blank\" rel=\"noopener noreferrer\">@looksanddiy<\/a> vedrai che <strong>cucire la tua coperta <\/strong>in maniera <strong>facile <\/strong>e semplice \u00e8 possibile. Per cominciare, avrai bisogno della macchina da cucire, 2 m di <strong><a href=\"https:\/\/www.katia.com\/IT\/fabric-tessuto-granny-square-pastel-colors-2161-2.html\" target=\"_blank\" rel=\"noopener noreferrer\">tessuto Granny<\/a><\/strong> e 190 cm di un tessuto morbido e caldo come lo <em><a href=\"https:\/\/www.katia.com\/IT\/fabric-tessuto-effetto-peluche-fleece-sherpa-cream-2197-1.html\" target=\"_blank\" rel=\"noopener noreferrer\">shearling<\/a><\/em> color maquillage. In pi\u00f9, assicurati di tenere pronte le tue <a href=\"https:\/\/www.katia.com\/IT\/articulo-forbici-da-sarto-in-acciaio-nero-28-cm-7327.html\" target=\"_blank\" rel=\"noopener noreferrer\">forbici<\/a>, il tuo <a href=\"https:\/\/www.katia.com\/IT\/articulo-metro-da-sarto-150-cm-60-pollici-7474.html\" target=\"_blank\" rel=\"noopener noreferrer\">metro<\/a>, i tuoi <a href=\"https:\/\/www.katia.com\/IT\/articulo-scatola-con-60-spilli-da-cucito-in-6-colori-7477.html\" target=\"_blank\" rel=\"noopener noreferrer\">spilli<\/a> e la voglia di passare un felice <strong>pomeriggio di cucito.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5669\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/it\/wp-content\/uploads\/2023\/02\/feat-fabrics-640x640-1.jpg?resize=640%2C640&#038;ssl=1\" alt=\"Come cucire una coperta \" width=\"640\" height=\"640\" data-recalc-dims=\"1\" \/><\/p>\n<p>Il passo dopo passo viene dalla mano di Esther (<a href=\"https:\/\/cutt.ly\/k-IG-looksanddiy\" target=\"_blank\" rel=\"noopener noreferrer\">@looksanddipatterns<\/a>), la disegnatrice anima del marchio di modelli <a href=\"https:\/\/academia.looksanddiy.com\/course-cat\/patrones\/\" target=\"_blank\" rel=\"noopener noreferrer\">Looks and DIY<\/a>. In pi\u00f9, tutti i suoi modelli sono disponibili in spagnolo e in inglese. Trova i cartamodelli pronti da stampare e cucire nel suo <a href=\"https:\/\/www.etsy.com\/shop\/looksanddiyPATTERNS\" target=\"_blank\" rel=\"noopener noreferrer\">shop<\/a>.<\/p>\n<p style=\"padding-left: 40px;\">Mi presento, sono <a href=\"https:\/\/academia.looksanddiy.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Esther Mart\u00ednez<\/a>, istruttrice di <strong>cucito e modellistica<\/strong>. Sono premio straordinario della comunit\u00e0 Autonoma di Aragona (Spagna), he partecipato come relatrice alla Fiera Creativa e sono apparsa sulla rivista Elle.<\/p>\n<p style=\"padding-left: 40px;\">Per me cucire \u00e8 una scialuppa di salvataggio, un momento di disconnessione e pace incomparabile. Ho cominciato a cucire da piccolina vedendo mia madre e mia nonna fra i tessuti e da allora non ho pi\u00f9 smesso. Ho studiato Economia Aziendale e Management e poi ho deciso di dare una svolta alla mia carriera, studiando modellistica e design di moda. Creo <strong>modelli di cucito <\/strong>alla moda con <strong>istruzioni chiare <\/strong>e dettagliate per le donne che decidono di cucire i propri capi, per\u00f2 non sanno come creare un modello o da dove cominciare.<\/p>\n<h3 style=\"padding-left: 40px;\"><strong>Dove puoi trovare i miei modelli?<\/strong><\/h3>\n<p style=\"padding-left: 40px;\">Puoi trovare la mia linea di modelli nella mia <a href=\"https:\/\/cutt.ly\/k-academia-looksanddiy\" target=\"_blank\" rel=\"noopener noreferrer\">Accademia online<\/a>. Se cerchi nel cucito un rifugio di calma e disconnessione dalla tua giornata impegnativa e desideri cucire con le tue mani capi che ti vestano alla perfezione, ti posso aiutare. Ti far\u00f2 creare un <strong>guardaroba unico, personale e sostenibile<\/strong> del quale sarai orgogliosa al 100% Mi piacerebbe connettermi con te!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5670\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/it\/wp-content\/uploads\/2023\/02\/Slide-fabrics-lovers.jpg?resize=1020%2C266&#038;ssl=1\" alt=\"Come cucire una coperta \" width=\"1020\" height=\"266\" data-recalc-dims=\"1\" \/><\/p>\n<h2><strong>Impara come cucire una coperta morbida, bella e calda <\/strong><\/h2>\n<p><strong>Materiale<\/strong><\/p>\n<p>Le misure che seguiremo per cucire la coperta sono le seguenti:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.katia.com\/IT\/fabric-tessuto-granny-square-pastel-colors-2161-2.html\" target=\"_blank\" rel=\"noopener noreferrer\">Tessuto Granny<\/a>: 2 metri di lunghezza e 1\u00b450 metri di larghezza<\/li>\n<li><a href=\"https:\/\/www.katia.com\/IT\/fabric-tessuto-effetto-peluche-fleece-sherpa-cream-2197-1.html\" target=\"_blank\" rel=\"noopener noreferrer\">Tessuto Shearling:<\/a> 1\u00b490 di lunghezza x 1\u00b440 di larghezza.<\/li>\n<li>Filo<\/li>\n<li>Oltre ai classici accessori da cucito: <a href=\"https:\/\/www.katia.com\/IT\/articulo-forbici-da-sarto-in-acciaio-nero-28-cm-7327.html\" target=\"_blank\" rel=\"noopener noreferrer\">forbici<\/a>, <a href=\"https:\/\/www.katia.com\/IT\/articulo-metro-da-sarto-150-cm-60-pollici-7474.html\" target=\"_blank\" rel=\"noopener noreferrer\">nastro da sarta<\/a>, <a href=\"https:\/\/www.katia.com\/IT\/articulo-scatola-con-60-spilli-da-cucito-in-6-colori-7477.html\" target=\"_blank\" rel=\"noopener noreferrer\">spille<\/a>, macchina da cucito, ecc.<\/li>\n<\/ul>\n<h3><strong>Raccomandazioni<\/strong><\/h3>\n<p>Se cerchi i parametri che <a href=\"https:\/\/looksanddiy.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Esther<\/a> ha utilizzato sulla sua macchina da cucire e consigli per cucire il tessuto peloso, puoi trovare un reel <a href=\"https:\/\/www.instagram.com\/looksanddiy\/\" target=\"_blank\" rel=\"noopener noreferrer\">su instagram<\/a> con tutti i miei consigli pratici e utili.<\/p>\n<p>Per cucire questi tessuti con pi\u00f9 facilit\u00e0, sarebbe meglio utilizzare un <strong>piedino a rullo <\/strong>e <strong>imbastire <\/strong>i tessuti perch\u00e9 non si muovano durante la cucitura. Questo \u00e8 molto importante poich\u00e9 il tessuto <em>granny<\/em> ha una trama molto aperta e il tessuto peloso \u00e8 elastico, quindi cede facilmente se non si tratta con cura il tessuto.<\/p>\n<p>Applicando questi <strong>due consigli <\/strong>non ci saranno problemi nel cucire.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19738 size-full\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/es\/wp-content\/uploads\/2023\/02\/GRANNY-SQUARES-BLANKET_2.jpg?resize=550%2C850&#038;ssl=1\" alt=\"C\u00f3mo coser una manta\" width=\"550\" height=\"850\" data-recalc-dims=\"1\" \/><\/p>\n<h3><strong>Realizzazione | Come cucire una coperta<\/strong><\/h3>\n<p>1. Per iniziare, <strong>cerca il centro <\/strong>di ciascun lato di entrambi tessuti (puoi piegarlo su s\u00e9 stesso per trovare il centro) e marcalo con uno spillo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19725 size-full\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/es\/wp-content\/uploads\/2023\/02\/1.jpg?resize=1020%2C680&#038;ssl=1\" alt=\"Come cucire una coperta\" width=\"1020\" height=\"680\" data-recalc-dims=\"1\" \/><\/p>\n<p>2. Comincia da uno dei lati lunghi, <strong>affaccia entrambi i tessuti diritto contro diritto, <\/strong>facendo combaciare lo spillo centrale. Fissa con gli spilli.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19726 size-full\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/es\/wp-content\/uploads\/2023\/02\/2.jpg?resize=1020%2C339&#038;ssl=1\" alt=\"Fissa con gli spilli\" width=\"1020\" height=\"339\" data-recalc-dims=\"1\" \/><\/p>\n<p>3. Assicurati di lasciare 1 cm scucito all\u2019inizio e alla fine di questa linea. Cuci con un <strong>punto diritto <\/strong>rifinendo l\u2019inizio e la fine.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19727 size-full\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/es\/wp-content\/uploads\/2023\/02\/3.jpg?resize=1020%2C680&#038;ssl=1\" alt=\"punto diritto\" width=\"1020\" height=\"680\" data-recalc-dims=\"1\" \/><\/p>\n<p>4. Ripeti i passaggi precedenti su tutti i lati. Su uno di quelli, lascia <strong>20 cm scuciti<\/strong> in modo da poter poi risvoltare la coperta attraverso questa apertura.\u00a0<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19728 size-full\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/es\/wp-content\/uploads\/2023\/02\/4.jpg?resize=1020%2C339&#038;ssl=1\" alt=\"\" width=\"1020\" height=\"339\" data-recalc-dims=\"1\" \/><\/p>\n<p>Ecco come si vedranno gli angoli dopo aver affacciato i lati:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19729 size-full\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/es\/wp-content\/uploads\/2023\/02\/5.jpg?resize=1020%2C339&#038;ssl=1\" alt=\"\" width=\"1020\" height=\"339\" data-recalc-dims=\"1\" \/><\/p>\n<p>5. Poi, diamo la forma agli angoli. Con l\u2019aiuto di una squadra, fai una linea seguendo la diagonale che si forma piegando il tessuto dall\u2019angolo. Marca con una penna cancellabile. Il risultato \u00e8 una linea retta (forma un angolo di 90\u00b0). Marca e <strong>cuci <\/strong>in questo modo i <strong>4 angoli<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19730 size-full\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/es\/wp-content\/uploads\/2023\/02\/6.jpg?resize=1020%2C339&#038;ssl=1\" alt=\"forma agli angoli\" width=\"1020\" height=\"339\" data-recalc-dims=\"1\" \/><\/p>\n<p>6. <strong>Taglia <\/strong>il tessuto in eccesso e fai un taglio verso la punta dell\u2019angolo cos\u00ec che la cucitura rimanga perfetta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19731 size-full\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/es\/wp-content\/uploads\/2023\/02\/7.jpg?resize=1020%2C680&#038;ssl=1\" alt=\"punta dell\u2019angolo \" width=\"1020\" height=\"680\" data-recalc-dims=\"1\" \/><\/p>\n<p>7. Una volta terminata la confezione dell\u2019interno, risvolta la coperta attraverso lo spazio lasciato aperto. Ecco come si vedono gli angoli dopo aver <strong>risvoltato la coperta<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19732 size-full\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/es\/wp-content\/uploads\/2023\/02\/8.jpg?resize=1020%2C680&#038;ssl=1\" alt=\"risvolta la coperta\" width=\"1020\" height=\"680\" data-recalc-dims=\"1\" \/><\/p>\n<p>8. Chiudi l\u2019apertura a mano con un <strong>punto nascosto<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19733 size-full\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/es\/wp-content\/uploads\/2023\/02\/9.jpg?resize=1020%2C680&#038;ssl=1\" alt=\"Come cucire una coperta\" width=\"1020\" height=\"680\" data-recalc-dims=\"1\" \/><\/p>\n<p>9. Infine, per rifinire le cuciture e mantenere il margine desiderato attorno a tutta la coperta, fai una <strong>cucitura di rinforzo<\/strong>. Prima fissa con gli spilli e imbastisci.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19734 size-full\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/es\/wp-content\/uploads\/2023\/02\/10.jpg?resize=1020%2C339&#038;ssl=1\" alt=\"cucitura di rinforzo\" width=\"1020\" height=\"339\" data-recalc-dims=\"1\" \/><\/p>\n<p>Ed ecco pronta la tua coperta, questo \u00e8 il risultato!<\/p>\n<p>Speriamo che ti sia piaciuta e che tu ti possa divertire a realizzare la tua <strong>coperta Granny<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19736 size-full\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/es\/wp-content\/uploads\/2023\/02\/GRANNY-SQUARES-BLANKET.jpg?resize=550%2C850&#038;ssl=1\" alt=\"Come cucire una coperta\" width=\"550\" height=\"850\" data-recalc-dims=\"1\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cosa ti viene in mente quando pensi a \u201cdivano, coperta e film?\u201d Se la risposta \u00e8 \u201crelax!\u201d Questo post \u00e8 per te. Oggi ti proponiamo come cucire una coperta stile Granny cos\u00ec tanto di moda. Grazie al modello passo dopo passo che ha creato Esther di @looksanddiy vedrai che cucire la tua coperta in maniera&hellip;<\/p>\n","protected":false},"author":2,"featured_media":264042,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[12006,12002,12007,12023,12011,12014,12024,12010],"tags":[10877,11110,11420,11515,11565,11641,11696,10780],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Come cucire una coperta in stile Granny \ufe0f Tutorial facile | Katia Fabrics<\/title>\n<meta name=\"description\" content=\"Scopri come cucire una coperta stile Granny cos\u00ec tanto di moda. Grazie al modello passo dopo passo che ha creato Esther di @looksanddiy!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.katia.com\/blog\/it\/come-cucire-una-coperta-granny-tutorial-facile\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come cucire una coperta in stile Granny \ufe0f Tutorial facile | Katia Fabrics\" \/>\n<meta property=\"og:description\" content=\"Scopri come cucire una coperta stile Granny cos\u00ec tanto di moda. Grazie al modello passo dopo passo che ha creato Esther di @looksanddiy!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.katia.com\/blog\/it\/come-cucire-una-coperta-granny-tutorial-facile\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog di cucito, uncinetto e lavoro a maglia | Blog di Katia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KatiaYarns\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-03T06:00:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-14T09:33:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/wp-content\/uploads\/2023\/06\/feat-fabrics-640x640-1-26.jpg?fit=640%2C640&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marisa Guerrero | Katia Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@katiayarns\" \/>\n<meta name=\"twitter:site\" content=\"@katiayarns\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marisa Guerrero | Katia Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/come-cucire-una-coperta-granny-tutorial-facile\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/come-cucire-una-coperta-granny-tutorial-facile\/\"},\"author\":{\"name\":\"Marisa Guerrero | Katia Team\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#\/schema\/person\/7f7e1104097c12cdcd6f14538e89f243\"},\"headline\":\"Come cucire una coperta stile Granny? \u00c8 facile come seguire il passo dopo passo gratuito di @looksanddiy\",\"datePublished\":\"2023-03-03T06:00:03+00:00\",\"dateModified\":\"2023-06-14T09:33:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/come-cucire-una-coperta-granny-tutorial-facile\/\"},\"wordCount\":777,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#organization\"},\"keywords\":[\"peluche\",\"granny\",\"imbastire\",\"angoli\",\"spilla\",\"Passo dopo passo\",\"shearling\",\"coperta\"],\"articleSection\":[\"Premium Designers\",\"Katia 100% You\",\"Craft Lovers\",\"Moda e Accessori\",\"Tutorial e Modelli\",\"Cucito\",\"Casa e Decorazione\",\"Tendenze Autunno Inverno\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.katia.com\/blog\/it\/come-cucire-una-coperta-granny-tutorial-facile\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/come-cucire-una-coperta-granny-tutorial-facile\/\",\"url\":\"https:\/\/www.katia.com\/blog\/it\/come-cucire-una-coperta-granny-tutorial-facile\/\",\"name\":\"Come cucire una coperta in stile Granny \ufe0f Tutorial facile | Katia Fabrics\",\"isPartOf\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#website\"},\"datePublished\":\"2023-03-03T06:00:03+00:00\",\"dateModified\":\"2023-06-14T09:33:47+00:00\",\"description\":\"Scopri come cucire una coperta stile Granny cos\u00ec tanto di moda. Grazie al modello passo dopo passo che ha creato Esther di @looksanddiy!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/come-cucire-una-coperta-granny-tutorial-facile\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.katia.com\/blog\/it\/come-cucire-una-coperta-granny-tutorial-facile\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/come-cucire-una-coperta-granny-tutorial-facile\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/www.katia.com\/blog\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come cucire una coperta stile Granny? \u00c8 facile come seguire il passo dopo passo gratuito di @looksanddiy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#website\",\"url\":\"https:\/\/www.katia.com\/blog\/it\/\",\"name\":\"www.katia.com\",\"description\":\"Tu blog de crochet, punto, costura o macram\u00e9 con tutoriales para aprender e ideas para tejer y coser piezas \u00fanicas. Blog de Katia, para esp\u00edritus creativos.\",\"publisher\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.katia.com\/blog\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#organization\",\"name\":\"Fil Katia, S.A\",\"url\":\"https:\/\/www.katia.com\/blog\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg\",\"contentUrl\":\"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg\",\"width\":\"600\",\"height\":\"1200\",\"caption\":\"Fil Katia, S.A\"},\"image\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/KatiaYarns\/\",\"https:\/\/twitter.com\/katiayarns\",\"http:\/\/instagram.com\/katiayarns\",\"https:\/\/www.linkedin.com\/company\/fil-katia\/\",\"https:\/\/www.pinterest.com\/KatiaYarns\/\",\"https:\/\/www.youtube.com\/c\/KatiaYarnsFabrics\/videos\",\"https:\/\/www.tiktok.com\/@katiacrafts\",\"https:\/\/www.instagram.com\/katiafabrics\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#\/schema\/person\/7f7e1104097c12cdcd6f14538e89f243\",\"name\":\"Marisa Guerrero | Katia Team\",\"description\":\"At Katia, we've been creating yarns for crafts for over 70 years. Each season, we develop new high-quality yarns under the Katia, WOW!, Lanas Stop, and Concept by Katia brands. Inspired by our wide and varied collection of yarns, we also publish knitting and crochet pattern magazines for garments and accessories for Women, Men, Kids, Babies, and Home.\",\"url\":\"https:\/\/www.katia.com\/blog\/it\/author\/nuriacastello\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come cucire una coperta in stile Granny \ufe0f Tutorial facile | Katia Fabrics","description":"Scopri come cucire una coperta stile Granny cos\u00ec tanto di moda. Grazie al modello passo dopo passo che ha creato Esther di @looksanddiy!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.katia.com\/blog\/it\/come-cucire-una-coperta-granny-tutorial-facile\/","og_locale":"it_IT","og_type":"article","og_title":"Come cucire una coperta in stile Granny \ufe0f Tutorial facile | Katia Fabrics","og_description":"Scopri come cucire una coperta stile Granny cos\u00ec tanto di moda. Grazie al modello passo dopo passo che ha creato Esther di @looksanddiy!","og_url":"https:\/\/www.katia.com\/blog\/it\/come-cucire-una-coperta-granny-tutorial-facile\/","og_site_name":"Blog di cucito, uncinetto e lavoro a maglia | Blog di Katia","article_publisher":"https:\/\/www.facebook.com\/KatiaYarns\/","article_published_time":"2023-03-03T06:00:03+00:00","article_modified_time":"2023-06-14T09:33:47+00:00","og_image":[{"width":640,"height":640,"url":"https:\/\/i0.wp.com\/www.katia.com\/blog\/wp-content\/uploads\/2023\/06\/feat-fabrics-640x640-1-26.jpg?fit=640%2C640&ssl=1","type":"image\/jpeg"}],"author":"Marisa Guerrero | Katia Team","twitter_card":"summary_large_image","twitter_creator":"@katiayarns","twitter_site":"@katiayarns","twitter_misc":{"Scritto da":"Marisa Guerrero | Katia Team","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.katia.com\/blog\/it\/come-cucire-una-coperta-granny-tutorial-facile\/#article","isPartOf":{"@id":"https:\/\/www.katia.com\/blog\/it\/come-cucire-una-coperta-granny-tutorial-facile\/"},"author":{"name":"Marisa Guerrero | Katia Team","@id":"https:\/\/www.katia.com\/blog\/it\/#\/schema\/person\/7f7e1104097c12cdcd6f14538e89f243"},"headline":"Come cucire una coperta stile Granny? \u00c8 facile come seguire il passo dopo passo gratuito di @looksanddiy","datePublished":"2023-03-03T06:00:03+00:00","dateModified":"2023-06-14T09:33:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.katia.com\/blog\/it\/come-cucire-una-coperta-granny-tutorial-facile\/"},"wordCount":777,"commentCount":0,"publisher":{"@id":"https:\/\/www.katia.com\/blog\/it\/#organization"},"keywords":["peluche","granny","imbastire","angoli","spilla","Passo dopo passo","shearling","coperta"],"articleSection":["Premium Designers","Katia 100% You","Craft Lovers","Moda e Accessori","Tutorial e Modelli","Cucito","Casa e Decorazione","Tendenze Autunno Inverno"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.katia.com\/blog\/it\/come-cucire-una-coperta-granny-tutorial-facile\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.katia.com\/blog\/it\/come-cucire-una-coperta-granny-tutorial-facile\/","url":"https:\/\/www.katia.com\/blog\/it\/come-cucire-una-coperta-granny-tutorial-facile\/","name":"Come cucire una coperta in stile Granny \ufe0f Tutorial facile | Katia Fabrics","isPartOf":{"@id":"https:\/\/www.katia.com\/blog\/it\/#website"},"datePublished":"2023-03-03T06:00:03+00:00","dateModified":"2023-06-14T09:33:47+00:00","description":"Scopri come cucire una coperta stile Granny cos\u00ec tanto di moda. Grazie al modello passo dopo passo che ha creato Esther di @looksanddiy!","breadcrumb":{"@id":"https:\/\/www.katia.com\/blog\/it\/come-cucire-una-coperta-granny-tutorial-facile\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.katia.com\/blog\/it\/come-cucire-una-coperta-granny-tutorial-facile\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.katia.com\/blog\/it\/come-cucire-una-coperta-granny-tutorial-facile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.katia.com\/blog\/it\/"},{"@type":"ListItem","position":2,"name":"Come cucire una coperta stile Granny? \u00c8 facile come seguire il passo dopo passo gratuito di @looksanddiy"}]},{"@type":"WebSite","@id":"https:\/\/www.katia.com\/blog\/it\/#website","url":"https:\/\/www.katia.com\/blog\/it\/","name":"www.katia.com","description":"Tu blog de crochet, punto, costura o macram\u00e9 con tutoriales para aprender e ideas para tejer y coser piezas \u00fanicas. Blog de Katia, para esp\u00edritus creativos.","publisher":{"@id":"https:\/\/www.katia.com\/blog\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.katia.com\/blog\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.katia.com\/blog\/it\/#organization","name":"Fil Katia, S.A","url":"https:\/\/www.katia.com\/blog\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.katia.com\/blog\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg","contentUrl":"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg","width":"600","height":"1200","caption":"Fil Katia, S.A"},"image":{"@id":"https:\/\/www.katia.com\/blog\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KatiaYarns\/","https:\/\/twitter.com\/katiayarns","http:\/\/instagram.com\/katiayarns","https:\/\/www.linkedin.com\/company\/fil-katia\/","https:\/\/www.pinterest.com\/KatiaYarns\/","https:\/\/www.youtube.com\/c\/KatiaYarnsFabrics\/videos","https:\/\/www.tiktok.com\/@katiacrafts","https:\/\/www.instagram.com\/katiafabrics"]},{"@type":"Person","@id":"https:\/\/www.katia.com\/blog\/it\/#\/schema\/person\/7f7e1104097c12cdcd6f14538e89f243","name":"Marisa Guerrero | Katia Team","description":"At Katia, we've been creating yarns for crafts for over 70 years. Each season, we develop new high-quality yarns under the Katia, WOW!, Lanas Stop, and Concept by Katia brands. Inspired by our wide and varied collection of yarns, we also publish knitting and crochet pattern magazines for garments and accessories for Women, Men, Kids, Babies, and Home.","url":"https:\/\/www.katia.com\/blog\/it\/author\/nuriacastello\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.katia.com\/blog\/wp-content\/uploads\/2023\/06\/feat-fabrics-640x640-1-26.jpg?fit=640%2C640&ssl=1","jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/peUVQy-16GJ","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/posts\/264041"}],"collection":[{"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/comments?post=264041"}],"version-history":[{"count":0,"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/posts\/264041\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/media\/264042"}],"wp:attachment":[{"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/media?parent=264041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/categories?post=264041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/tags?post=264041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}