{"id":263695,"date":"2023-01-09T12:49:27","date_gmt":"2023-01-09T11:49:27","guid":{"rendered":"https:\/\/www.katia.com\/blog\/concorso-modelli-di-cucito-accessori-creativo\/"},"modified":"2023-06-14T11:33:04","modified_gmt":"2023-06-14T09:33:04","slug":"concorso-modelli-di-cucito-accessori-creativo","status":"publish","type":"post","link":"https:\/\/www.katia.com\/blog\/it\/concorso-modelli-di-cucito-accessori-creativo\/","title":{"rendered":"Concorso Modelli di Cucito \u2702 Pubblica il tuo disegno di accessori pi\u00f9 creativo sulla rivista Katia Fabrics!"},"content":{"rendered":"<p>Ti appassionano il design, il cucito e la confezione di accessori? Se desideri vedere pubblicato il tuo modello di cucito sulla <a href=\"https:\/\/www.katia.com\/IT\/riviste.html?tipo[]=FABRICS\" target=\"_blank\" rel=\"noopener noreferrer\">prossima rivista di Katia Fabrics<\/a>, il <em>nostro<\/em> <em>concorso creativo <\/em>di Katia Fabrics \u00e8 per te. Partecipa a <em>Katia Fabrics Sewing Pattern Spring\u00b7Summer 24<\/em><strong>,<\/strong> la 1\u00aa edizione del nostro <strong>Concorso Modelli di Cucito. <\/strong>Devi soltanto creare il <a href=\"https:\/\/www.katia.com\/IT\/cartamodelli-tessuti.html?universo[]=A&amp;universo[]=KS\" target=\"_blank\" rel=\"noopener noreferrer\">modello di un <strong>accessorio<\/strong><\/a>: una <em>borsa, <\/em>un<em> marsupio, <\/em>uno <em>zaino, <\/em>ecc. Se il tuo modello risulter\u00e0 vincitore, oltre a veder pubblicato il tuo modello sulla prossima rivista di Katia Fabrics, riceverai <strong>150\u202f\u20ac in prodotti Katia a tua scelta. \u00a0<\/strong><\/p>\n<p>Sosteniamo il tuo talento! Pubblicare un modello di cucito <strong>creato per te<\/strong> \u00e8 una grande opportunit\u00e0 per farti conoscere. Entra nel mondo del design con Katia Fabrics Sewing Pattern Awards Spring-Summer 2024!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5536\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/it\/wp-content\/uploads\/2023\/01\/Katia-Fabrics-Sewing-Pattern-copia.jpg?resize=600%2C615&#038;ssl=1\" alt=\"Concorso Modelli di Cucito\" width=\"600\" height=\"615\" data-recalc-dims=\"1\" \/><\/p>\n<h2><strong>Requisiti di Partecipazione Concorso Modelli di Cucito<\/strong><\/h2>\n<h3>1. Paternit\u00e0 del modello<\/h3>\n<p>Il modello deve essere al 100% <strong>una tua creazione<\/strong>.<\/p>\n<h3>2. Dimensioni reali e formato PDF<\/h3>\n<p>Genera un <strong>PDF<\/strong> con il cartamodello o le linee del modello con le misure del tuo accessorio con margini di cucitura inclusi <strong>a grandezza naturale. <\/strong><\/p>\n<ul>\n<li>Se utilizzi un <strong>programma di editing<\/strong>, disegna il tuo modello in formato digitale con misure reali. \u00a0<\/li>\n<li>Se preferisci, <strong>disegna a mano il tuo modello <\/strong>a grandezza naturale in<strong> formato A4, scansionalo e crea un PDF<\/strong>.<\/li>\n<\/ul>\n<p>\u00c8 gradito che i modello sia stato <strong>confezionato in precedenza<\/strong> affinch\u00e9 tu possa mostrarci come appare realizzato.<\/p>\n<h3>3. Progetto per Canvas Slim<\/h3>\n<p>Libera la fantasia e sorprendici! <a href=\"https:\/\/www.katia.com\/IT\/cartamodelli-tessuti.html?universo[]=A&amp;universo[]=KS\" target=\"_blank\" rel=\"noopener noreferrer\">Crea un accessorio 100% YOU<\/a> (fatto fa te): <strong>zaini, borse, marsupi, portafogli, porta carte, borse porta lavori, borsa per sarte, porta vivande, custodie per laptop o cellulare <\/strong><strong>ecc., <\/strong>Tieni presente che il tessuto finale in cui sar\u00e0 creato il tuo modello \u00e8 il <a href=\"https:\/\/www.katia.com\/IT\/tessuti.html?linea[]=CANVAS\" target=\"_blank\" rel=\"noopener noreferrer\"><em>Canvas Slim<\/em><\/a>, una<strong> loneta<\/strong> ideale per la creazione di accessori, grazie alla sua resistenza e durabilit\u00e0.<\/p>\n<p><a href=\"https:\/\/www.katia.com\/IT\/tessuti.html?linea[]=CANVAS\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/i1.wp.com\/www.katia.com\/blog\/es\/wp-content\/uploads\/2022\/12\/blogpics-KATIA-FABRICS-SEWING-PATTERN-tela.jpg?resize=600%2C800&amp;ssl=1\" alt=\"Concurso de Patrones de Costura\" width=\"600\" height=\"800\" \/><\/a><\/p>\n<h2><strong>Partecipa a <\/strong><em>Katia Fabrics Sewing Pattern<\/em><strong>!<\/strong><\/h2>\n<ol>\n<li>Crea un\u00a0<em>modello di cucito al 100% creato da te<\/em> in dimensione reale in formato digitale PDF.<\/li>\n<li>Clicca sul seguente link per <strong>completare il <a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSemKlf7DT1vWLv83sKFDqNYhQ4UzbPjlCLbqCiY2QEIIpSTYg\/viewform?usp=sf_link\" target=\"_blank\" rel=\"noopener noreferrer\">modulo <\/a><\/strong><strong><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSemKlf7DT1vWLv83sKFDqNYhQ4UzbPjlCLbqCiY2QEIIpSTYg\/viewform?usp=sf_link\" target=\"_blank\" rel=\"noopener noreferrer\">di partecipazione<\/a> prima del <\/strong><strong>15 <u>febbraio 2023<\/u><\/strong>.\u00a0Ricorda di aggiungere il <strong>tuo<\/strong> <strong>modello di cucito<\/strong> misura reale in formato digitale PDF e delle <strong>foto <\/strong>di come hai cucito il tuo accessorio.<\/li>\n<\/ol>\n<p style=\"padding-left: 40px;\"><span style=\"font-size: 18pt;\"><a style=\"color: #ff0000;\" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSemKlf7DT1vWLv83sKFDqNYhQ4UzbPjlCLbqCiY2QEIIpSTYg\/viewform?usp=sf_link\"><strong>DESIDERO PARTECIPARE!<\/strong><\/a><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5524\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/it\/wp-content\/uploads\/2023\/01\/slide-posts-fabrics-.jpg?resize=1020%2C266&#038;ssl=1\" alt=\"Concorso Modelli di Cucito\" width=\"1020\" height=\"266\" data-recalc-dims=\"1\" \/><\/p>\n<h3><strong>Come selezioniamo il vincitore?<\/strong><\/h3>\n<p>I membri del <em>Team di Design di Katia Fabrics <\/em>selezionano i <strong>finalisti<\/strong> fra <a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSemKlf7DT1vWLv83sKFDqNYhQ4UzbPjlCLbqCiY2QEIIpSTYg\/viewform?usp=sf_link\" target=\"_blank\" rel=\"noopener noreferrer\">di partecipazione<\/a>. Verr\u00e0 valutato in particolare il fattore sorpresa. Vogliamo premiare il tuo lato pi\u00f9 creativo, per questo, Sorprendici! Terremo anche molto in considerazione che il modello si adatti al <a href=\"https:\/\/www.katia.com\/IT\/tessuti.html?linea[]=CANVAS\" target=\"_blank\" rel=\"noopener noreferrer\">tessuto <\/a><strong><a href=\"https:\/\/www.katia.com\/IT\/tessuti.html?linea[]=CANVAS\">Canvas Slim<\/a>.<\/strong> Con questi criteri, scegliamo il <strong>vincitore<\/strong>.<\/p>\n<p><strong><span style=\"color: #ff0000;\">*<a style=\"color: #ff0000;\" href=\"https:\/\/www.katia.com\/blog\/it\/wp-content\/uploads\/2023\/01\/REGOLE-BASE-DEL-CONCORSO-IT.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Leggi qui le regole complete del concorso<\/a>.<\/span><\/strong><\/p>\n<h3><strong>Premio per il modello vincitore<\/strong><\/h3>\n<p>Se il tuo modello risulter\u00e0 vincitore, ti contatteremo. Da allora lavoreremo affinch\u00e9 possa essere presente sulla nuova <a href=\"https:\/\/www.katia.com\/IT\/riviste.html?tipo[]=FABRICS\" target=\"_blank\" rel=\"noopener noreferrer\">rivista di modelli di cucito di Katia Fabrics<\/a> primavera\/estate 24 come modello gratuito. Faremo conoscere il tuo talento sui nostri social, preparati per il meglio!<\/p>\n<p>In pi\u00f9 riceverai <strong>150\u202f\u20ac di prodotti Katia a scelta <\/strong>perch\u00e9 tu possa creare con questo materiale tutto ci\u00f2 che desideri.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ti appassionano il design, il cucito e la confezione di accessori? Se desideri vedere pubblicato il tuo modello di cucito sulla prossima rivista di Katia Fabrics, il nostro concorso creativo di Katia Fabrics \u00e8 per te. Partecipa a Katia Fabrics Sewing Pattern Spring\u00b7Summer 24, la 1\u00aa edizione del nostro Concorso Modelli di Cucito. Devi soltanto&hellip;<\/p>\n","protected":false},"author":2,"featured_media":263696,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[12002,12003,12004,12023,12011,12014],"tags":[10869,11194,11272,11496,11686,11687,10764,10777],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Concorso Modelli di Cucito \u2702 Pubblica il tuo disegno di accessori!<\/title>\n<meta name=\"description\" content=\"Ti appassionano il design, il cucito e la confezione di accessori? Partecipa del nostro Concorso Modelli di Cucito creativo di Katia Fabrics!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.katia.com\/blog\/it\/concorso-modelli-di-cucito-accessori-creativo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concorso Modelli di Cucito \u2702 Pubblica il tuo disegno di accessori!\" \/>\n<meta property=\"og:description\" content=\"Ti appassionano il design, il cucito e la confezione di accessori? Partecipa del nostro Concorso Modelli di Cucito creativo di Katia Fabrics!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.katia.com\/blog\/it\/concorso-modelli-di-cucito-accessori-creativo\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog di cucito, uncinetto e lavoro a maglia | Blog di Katia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KatiaYarns\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-09T11:49:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-14T09:33:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/wp-content\/uploads\/2023\/06\/Katia-Fabrics-Sewing-Pattern-copia-3.jpg?fit=600%2C615&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"615\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marisa Guerrero | Katia Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@katiayarns\" \/>\n<meta name=\"twitter:site\" content=\"@katiayarns\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marisa Guerrero | Katia Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/concorso-modelli-di-cucito-accessori-creativo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/concorso-modelli-di-cucito-accessori-creativo\/\"},\"author\":{\"name\":\"Marisa Guerrero | Katia Team\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#\/schema\/person\/7f7e1104097c12cdcd6f14538e89f243\"},\"headline\":\"Concorso Modelli di Cucito \u2702 Pubblica il tuo disegno di accessori pi\u00f9 creativo sulla rivista Katia Fabrics!\",\"datePublished\":\"2023-01-09T11:49:27+00:00\",\"dateModified\":\"2023-06-14T09:33:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/concorso-modelli-di-cucito-accessori-creativo\/\"},\"wordCount\":493,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#organization\"},\"keywords\":[\"Borse\",\"porta-gomitoli\",\"cartamodello\",\"custodia\",\"marsupi\",\"portafogli\",\"zaini\",\"creativit\u00e0\"],\"articleSection\":[\"Katia 100% You\",\"Rivista Katia\",\"Concorsi\",\"Moda e Accessori\",\"Tutorial e Modelli\",\"Cucito\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.katia.com\/blog\/it\/concorso-modelli-di-cucito-accessori-creativo\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/concorso-modelli-di-cucito-accessori-creativo\/\",\"url\":\"https:\/\/www.katia.com\/blog\/it\/concorso-modelli-di-cucito-accessori-creativo\/\",\"name\":\"Concorso Modelli di Cucito \u2702 Pubblica il tuo disegno di accessori!\",\"isPartOf\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#website\"},\"datePublished\":\"2023-01-09T11:49:27+00:00\",\"dateModified\":\"2023-06-14T09:33:04+00:00\",\"description\":\"Ti appassionano il design, il cucito e la confezione di accessori? Partecipa del nostro Concorso Modelli di Cucito creativo di Katia Fabrics!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/concorso-modelli-di-cucito-accessori-creativo\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.katia.com\/blog\/it\/concorso-modelli-di-cucito-accessori-creativo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/concorso-modelli-di-cucito-accessori-creativo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/www.katia.com\/blog\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concorso Modelli di Cucito \u2702 Pubblica il tuo disegno di accessori pi\u00f9 creativo sulla rivista Katia Fabrics!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#website\",\"url\":\"https:\/\/www.katia.com\/blog\/it\/\",\"name\":\"www.katia.com\",\"description\":\"Tu blog de crochet, punto, costura o macram\u00e9 con tutoriales para aprender e ideas para tejer y coser piezas \u00fanicas. Blog de Katia, para esp\u00edritus creativos.\",\"publisher\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.katia.com\/blog\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#organization\",\"name\":\"Fil Katia, S.A\",\"url\":\"https:\/\/www.katia.com\/blog\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg\",\"contentUrl\":\"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg\",\"width\":\"600\",\"height\":\"1200\",\"caption\":\"Fil Katia, S.A\"},\"image\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/KatiaYarns\/\",\"https:\/\/twitter.com\/katiayarns\",\"http:\/\/instagram.com\/katiayarns\",\"https:\/\/www.linkedin.com\/company\/fil-katia\/\",\"https:\/\/www.pinterest.com\/KatiaYarns\/\",\"https:\/\/www.youtube.com\/c\/KatiaYarnsFabrics\/videos\",\"https:\/\/www.tiktok.com\/@katiacrafts\",\"https:\/\/www.instagram.com\/katiafabrics\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#\/schema\/person\/7f7e1104097c12cdcd6f14538e89f243\",\"name\":\"Marisa Guerrero | Katia Team\",\"description\":\"At Katia, we've been creating yarns for crafts for over 70 years. Each season, we develop new high-quality yarns under the Katia, WOW!, Lanas Stop, and Concept by Katia brands. Inspired by our wide and varied collection of yarns, we also publish knitting and crochet pattern magazines for garments and accessories for Women, Men, Kids, Babies, and Home.\",\"url\":\"https:\/\/www.katia.com\/blog\/it\/author\/nuriacastello\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Concorso Modelli di Cucito \u2702 Pubblica il tuo disegno di accessori!","description":"Ti appassionano il design, il cucito e la confezione di accessori? Partecipa del nostro Concorso Modelli di Cucito creativo di Katia Fabrics!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.katia.com\/blog\/it\/concorso-modelli-di-cucito-accessori-creativo\/","og_locale":"it_IT","og_type":"article","og_title":"Concorso Modelli di Cucito \u2702 Pubblica il tuo disegno di accessori!","og_description":"Ti appassionano il design, il cucito e la confezione di accessori? Partecipa del nostro Concorso Modelli di Cucito creativo di Katia Fabrics!","og_url":"https:\/\/www.katia.com\/blog\/it\/concorso-modelli-di-cucito-accessori-creativo\/","og_site_name":"Blog di cucito, uncinetto e lavoro a maglia | Blog di Katia","article_publisher":"https:\/\/www.facebook.com\/KatiaYarns\/","article_published_time":"2023-01-09T11:49:27+00:00","article_modified_time":"2023-06-14T09:33:04+00:00","og_image":[{"width":600,"height":615,"url":"https:\/\/i0.wp.com\/www.katia.com\/blog\/wp-content\/uploads\/2023\/06\/Katia-Fabrics-Sewing-Pattern-copia-3.jpg?fit=600%2C615&ssl=1","type":"image\/jpeg"}],"author":"Marisa Guerrero | Katia Team","twitter_card":"summary_large_image","twitter_creator":"@katiayarns","twitter_site":"@katiayarns","twitter_misc":{"Scritto da":"Marisa Guerrero | Katia Team","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.katia.com\/blog\/it\/concorso-modelli-di-cucito-accessori-creativo\/#article","isPartOf":{"@id":"https:\/\/www.katia.com\/blog\/it\/concorso-modelli-di-cucito-accessori-creativo\/"},"author":{"name":"Marisa Guerrero | Katia Team","@id":"https:\/\/www.katia.com\/blog\/it\/#\/schema\/person\/7f7e1104097c12cdcd6f14538e89f243"},"headline":"Concorso Modelli di Cucito \u2702 Pubblica il tuo disegno di accessori pi\u00f9 creativo sulla rivista Katia Fabrics!","datePublished":"2023-01-09T11:49:27+00:00","dateModified":"2023-06-14T09:33:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.katia.com\/blog\/it\/concorso-modelli-di-cucito-accessori-creativo\/"},"wordCount":493,"commentCount":0,"publisher":{"@id":"https:\/\/www.katia.com\/blog\/it\/#organization"},"keywords":["Borse","porta-gomitoli","cartamodello","custodia","marsupi","portafogli","zaini","creativit\u00e0"],"articleSection":["Katia 100% You","Rivista Katia","Concorsi","Moda e Accessori","Tutorial e Modelli","Cucito"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.katia.com\/blog\/it\/concorso-modelli-di-cucito-accessori-creativo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.katia.com\/blog\/it\/concorso-modelli-di-cucito-accessori-creativo\/","url":"https:\/\/www.katia.com\/blog\/it\/concorso-modelli-di-cucito-accessori-creativo\/","name":"Concorso Modelli di Cucito \u2702 Pubblica il tuo disegno di accessori!","isPartOf":{"@id":"https:\/\/www.katia.com\/blog\/it\/#website"},"datePublished":"2023-01-09T11:49:27+00:00","dateModified":"2023-06-14T09:33:04+00:00","description":"Ti appassionano il design, il cucito e la confezione di accessori? Partecipa del nostro Concorso Modelli di Cucito creativo di Katia Fabrics!","breadcrumb":{"@id":"https:\/\/www.katia.com\/blog\/it\/concorso-modelli-di-cucito-accessori-creativo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.katia.com\/blog\/it\/concorso-modelli-di-cucito-accessori-creativo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.katia.com\/blog\/it\/concorso-modelli-di-cucito-accessori-creativo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.katia.com\/blog\/it\/"},{"@type":"ListItem","position":2,"name":"Concorso Modelli di Cucito \u2702 Pubblica il tuo disegno di accessori pi\u00f9 creativo sulla rivista Katia Fabrics!"}]},{"@type":"WebSite","@id":"https:\/\/www.katia.com\/blog\/it\/#website","url":"https:\/\/www.katia.com\/blog\/it\/","name":"www.katia.com","description":"Tu blog de crochet, punto, costura o macram\u00e9 con tutoriales para aprender e ideas para tejer y coser piezas \u00fanicas. Blog de Katia, para esp\u00edritus creativos.","publisher":{"@id":"https:\/\/www.katia.com\/blog\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.katia.com\/blog\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.katia.com\/blog\/it\/#organization","name":"Fil Katia, S.A","url":"https:\/\/www.katia.com\/blog\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.katia.com\/blog\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg","contentUrl":"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg","width":"600","height":"1200","caption":"Fil Katia, S.A"},"image":{"@id":"https:\/\/www.katia.com\/blog\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KatiaYarns\/","https:\/\/twitter.com\/katiayarns","http:\/\/instagram.com\/katiayarns","https:\/\/www.linkedin.com\/company\/fil-katia\/","https:\/\/www.pinterest.com\/KatiaYarns\/","https:\/\/www.youtube.com\/c\/KatiaYarnsFabrics\/videos","https:\/\/www.tiktok.com\/@katiacrafts","https:\/\/www.instagram.com\/katiafabrics"]},{"@type":"Person","@id":"https:\/\/www.katia.com\/blog\/it\/#\/schema\/person\/7f7e1104097c12cdcd6f14538e89f243","name":"Marisa Guerrero | Katia Team","description":"At Katia, we've been creating yarns for crafts for over 70 years. Each season, we develop new high-quality yarns under the Katia, WOW!, Lanas Stop, and Concept by Katia brands. Inspired by our wide and varied collection of yarns, we also publish knitting and crochet pattern magazines for garments and accessories for Women, Men, Kids, Babies, and Home.","url":"https:\/\/www.katia.com\/blog\/it\/author\/nuriacastello\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.katia.com\/blog\/wp-content\/uploads\/2023\/06\/Katia-Fabrics-Sewing-Pattern-copia-3.jpg?fit=600%2C615&ssl=1","jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/peUVQy-16B9","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/posts\/263695"}],"collection":[{"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/comments?post=263695"}],"version-history":[{"count":0,"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/posts\/263695\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/media\/263696"}],"wp:attachment":[{"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/media?parent=263695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/categories?post=263695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/tags?post=263695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}