{"id":260705,"date":"2022-04-07T06:42:25","date_gmt":"2022-04-07T04:42:25","guid":{"rendered":"https:\/\/www.katia.com\/blog\/katia-workshops-nei-negozi-uncinetto-maglia-cucito\/"},"modified":"2023-06-14T11:29:15","modified_gmt":"2023-06-14T09:29:15","slug":"katia-workshops-nei-negozi-uncinetto-maglia-cucito","status":"publish","type":"post","link":"https:\/\/www.katia.com\/blog\/it\/katia-workshops-nei-negozi-uncinetto-maglia-cucito\/","title":{"rendered":"Nuovi Katia Workshop nei negozi per imparare a realizzare 3 progetti all\u00b4uncinetto, a maglia e di cucito"},"content":{"rendered":"<p>Tre nuovi <em>Katia Workshop<\/em> <em>nei negozi<\/em> stano arrivando! Questa primavera impara a realizzare 3 interessanti progetti per <em>donna<\/em>, <em>bambina<\/em> e <em>neonato<\/em>. Qualunque sia il tuo livello, questi <strong>seminari<\/strong> sono un\u2019opportunit\u00e0 per<strong>\u00a0lavorare all\u00b4uncinetto <\/strong>una <em>coperta<\/em>, <strong>ai ferri<\/strong> <em>un top da donna con cappuccio <\/em>o <strong>cucire <\/strong>una <em>blusa con schiena scoperta<\/em>. Scopri nuovi punti e tecniche, ricevendo un\u2019attenzione personalizzata e una consulenza professionale nei negozi. Goditi un\u2019intera esperienza <strong>fai da te<\/strong> con i nuovi <strong>corsi<\/strong> nei negozi Katia! <a href=\"https:\/\/www.katia.com\/IT\/negozi-katia.html\" target=\"_blank\" rel=\"noopener noreferrer\">Chiedi ora al tuo negozio di fiducia<\/a> per scoprire se organizza uno dei <em>Workshop Katia<\/em>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4763\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/it\/wp-content\/uploads\/2022\/04\/workshops-katia-feat-640x640.jpg?resize=640%2C640&#038;ssl=1\" alt=\"Katia Workshop nei negozi\" width=\"640\" height=\"640\" data-recalc-dims=\"1\" \/><\/p>\n<h2>Katia Workshop nei negozi<\/h2>\n<p>Cosa puoi imparare in ogni <a href=\"https:\/\/www.katia.com\/IT\/negozi-katia.html\" target=\"_blank\" rel=\"noopener noreferrer\"><em>Katia Workshop nei negozi<\/em><\/a>? Questi sono i 3 <em>progetti<\/em> di <em>donna<\/em>, <em>bambina<\/em> e <em>bambino<\/em> che puoi fare nei <strong>corsi<\/strong> <strong>di maglia, uncinetto e cucito&#8230;<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4762\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/it\/wp-content\/uploads\/2022\/04\/workshops-2022-slide-1920x500.jpg?resize=1020%2C266&#038;ssl=1\" alt=\"Katia Workshop nei negozi\" width=\"1020\" height=\"266\" data-recalc-dims=\"1\" \/><\/p>\n<h2><strong>Workshop di uncinetto<\/strong><\/h2>\n<h3><strong><em>Coperta per bambini <\/em>United Cotton<\/strong><\/h3>\n<p>Livello: <em>Facile<\/em>. Questo <strong>seminario all\u00b4uncinetto<\/strong> \u00e8 il regalo perfetto per futuri genitori, zii, nonne&#8230; Divertitevi a fare una colorata <strong>coperta all\u00b4uncinetto per neonato<\/strong>. Il modo pi\u00f9 speciale per dare il benvenuto al nuovo membro della famiglia!<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/i2.wp.com\/www.katia.com\/blog\/es\/wp-content\/uploads\/2022\/04\/United_cotton_workshop.jpg?resize=1020%2C387&amp;ssl=1\" alt=\"Talleres en tiendas Katia\" \/><\/p>\n<h2><strong>Workshop <\/strong><strong>di maglia<\/strong><\/h2>\n<h3><strong><em>Maxi Top<\/em> con <em>Cappuccio <\/em>Babilonia<\/strong><\/h3>\n<p>Livello: <em>Intermedio<\/em>. Impara a lavorare ai ferri un<strong> maxi-top da donna<\/strong>, molto versatile, perfetto da abbinare ai capi stampati. Scopri in questo <strong>corso di maglia<\/strong> come aggiungere un <strong>cappuccio<\/strong> e dare un tocco moderno ai tuoi capi!<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/es\/wp-content\/uploads\/2022\/04\/Babilonia_workshop.jpg?resize=1020%2C387&amp;ssl=1\" alt=\"Talleres en tiendas Katia\" \/><\/p>\n<h2><strong>Workshop <\/strong><strong>di cucito<\/strong><\/h2>\n<h3><strong>Top <\/strong><strong>Senza Maniche <\/strong><strong>Katia Fabrics<\/strong><\/h3>\n<p>Livello: <em>Intermedio<\/em>. Sorprenditi cucendo un top<strong> estivo <\/strong>per <strong>ragazze<\/strong>, da 12 mesi a 4 anni, molto rinfrescante. Scopri come cucire un\u00b4originale blusa senza maniche a schiena aperta. Chiedi al<strong> negozio <\/strong>di <strong>tessuti<\/strong> pi\u00f9 vicino per questo <strong>seminario di cucito<\/strong>!<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/i1.wp.com\/www.katia.com\/blog\/es\/wp-content\/uploads\/2022\/04\/Fabrics_Jersey.jpg?resize=1020%2C387&amp;ssl=1\" alt=\"Talleres en tiendas Katia\" \/><\/p>\n<h2><strong>Trova negozi con corsi<\/strong><\/h2>\n<p>Ti iscrivi per goderti un\u00b4esperienza <em>fatta a mano al<\/em> 100%? <a href=\"https:\/\/www.katia.com\/IT\/negozi-katia.html\" target=\"_blank\" rel=\"noopener noreferrer\">Contatta o visita il tuo negozio abituale!<\/a> Per scoprire quali\u00a0<strong>negozi<\/strong>\u00a0organizzano i workshop Katia:<\/p>\n<ol>\n<li>Visita lo<strong><em>\u00a0<a href=\"https:\/\/www.katia.com\/IT\/negozi-katia.html\" target=\"_blank\" rel=\"noopener noreferrer\">store finder<\/a><\/em><\/strong>\u00a0sul nostro sito web.<\/li>\n<li>Seleziona la casella\u00a0<strong>Workshop Katia Academy<\/strong>\u00a0nel men\u00f9 a tendina.<\/li>\n<li>Seleziona PAESE, inserisci la tua citt\u00e0 e clicca su CERCA. In questo modo, la\u00a0<strong>mappa<\/strong>\u00a0mostra i negozi vicini che organizzano -tutti o alcuni- Katia Workshop.<\/li>\n<li>Quindi clicca su ciascuna icona K o consulta la tabella delle informazioni (sotto la mappa) per ottenere\u00a0<strong>l\u2019indirizzo<\/strong>\u00a0e i\u00a0<strong>recapiti<\/strong>\u00a0di questi negozi.\u00a0<\/li>\n<\/ol>\n<p>\u00a0I negozi sono sempre a tua disposizione per facilitare la tua esperienza di\u00a0<strong>apprendimento<\/strong>!<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/i1.wp.com\/www.katia.com\/blog\/it\/wp-content\/uploads\/2021\/04\/katia-workshops-map-IT.jpg?resize=737%2C708&amp;ssl=1\" alt=\"Corsi nei negozi\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tre nuovi Katia Workshop nei negozi stano arrivando! Questa primavera impara a realizzare 3 interessanti progetti per donna, bambina e neonato. Qualunque sia il tuo livello, questi seminari sono un\u2019opportunit\u00e0 per\u00a0lavorare all\u00b4uncinetto una coperta, ai ferri un top da donna con cappuccio o cucire una blusa con schiena scoperta. Scopri nuovi punti e tecniche, ricevendo&hellip;<\/p>\n","protected":false},"author":2,"featured_media":260706,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[12023],"tags":[11550,10780,11003,11390],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Katia Workshops nei negozi | 3 nuovi progetti all&#039;uncinetto, maglia e cucito<\/title>\n<meta name=\"description\" content=\"Tre nuovi Katia Workshop nei negozi! Impara a realizzare all&#039;uncinetto una coperta, ai ferri un top con cappuccio o cucire una blusa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.katia.com\/blog\/it\/katia-workshops-nei-negozi-uncinetto-maglia-cucito\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Katia Workshops nei negozi | 3 nuovi progetti all&#039;uncinetto, maglia e cucito\" \/>\n<meta property=\"og:description\" content=\"Tre nuovi Katia Workshop nei negozi! Impara a realizzare all&#039;uncinetto una coperta, ai ferri un top con cappuccio o cucire una blusa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.katia.com\/blog\/it\/katia-workshops-nei-negozi-uncinetto-maglia-cucito\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog di cucito, uncinetto e lavoro a maglia | Blog di Katia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KatiaYarns\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-07T04:42:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-14T09:29:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/wp-content\/uploads\/2023\/06\/workshops-katia-feat-640x640-7.jpg?fit=640%2C640&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marisa Guerrero | Katia Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@katiayarns\" \/>\n<meta name=\"twitter:site\" content=\"@katiayarns\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marisa Guerrero | Katia Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/katia-workshops-nei-negozi-uncinetto-maglia-cucito\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/katia-workshops-nei-negozi-uncinetto-maglia-cucito\/\"},\"author\":{\"name\":\"Marisa Guerrero | Katia Team\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#\/schema\/person\/7f7e1104097c12cdcd6f14538e89f243\"},\"headline\":\"Nuovi Katia Workshop nei negozi per imparare a realizzare 3 progetti all\u00b4uncinetto, a maglia e di cucito\",\"datePublished\":\"2022-04-07T04:42:25+00:00\",\"dateModified\":\"2023-06-14T09:29:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/katia-workshops-nei-negozi-uncinetto-maglia-cucito\/\"},\"wordCount\":392,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#organization\"},\"keywords\":[\"seminari\",\"coperta\",\"Negozi\",\"corsi\"],\"articleSection\":[\"Moda e Accessori\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.katia.com\/blog\/it\/katia-workshops-nei-negozi-uncinetto-maglia-cucito\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/katia-workshops-nei-negozi-uncinetto-maglia-cucito\/\",\"url\":\"https:\/\/www.katia.com\/blog\/it\/katia-workshops-nei-negozi-uncinetto-maglia-cucito\/\",\"name\":\"Katia Workshops nei negozi | 3 nuovi progetti all'uncinetto, maglia e cucito\",\"isPartOf\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#website\"},\"datePublished\":\"2022-04-07T04:42:25+00:00\",\"dateModified\":\"2023-06-14T09:29:15+00:00\",\"description\":\"Tre nuovi Katia Workshop nei negozi! Impara a realizzare all'uncinetto una coperta, ai ferri un top con cappuccio o cucire una blusa.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/katia-workshops-nei-negozi-uncinetto-maglia-cucito\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.katia.com\/blog\/it\/katia-workshops-nei-negozi-uncinetto-maglia-cucito\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/katia-workshops-nei-negozi-uncinetto-maglia-cucito\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/www.katia.com\/blog\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuovi Katia Workshop nei negozi per imparare a realizzare 3 progetti all\u00b4uncinetto, a maglia e di cucito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#website\",\"url\":\"https:\/\/www.katia.com\/blog\/it\/\",\"name\":\"www.katia.com\",\"description\":\"Il tuo blog di uncinetto, lavoro a maglia, cucito o macram\u00e8 con tutorial per imparare e idee per lavorare e cucire capi unici. Blog di Katia, per spiriti creativi\\n\",\"publisher\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.katia.com\/blog\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#organization\",\"name\":\"Fil Katia, S.A\",\"url\":\"https:\/\/www.katia.com\/blog\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg\",\"contentUrl\":\"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg\",\"width\":\"600\",\"height\":\"1200\",\"caption\":\"Fil Katia, S.A\"},\"image\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/KatiaYarns\/\",\"https:\/\/twitter.com\/katiayarns\",\"http:\/\/instagram.com\/katiayarns\",\"https:\/\/www.linkedin.com\/company\/fil-katia\/\",\"https:\/\/www.pinterest.com\/KatiaYarns\/\",\"https:\/\/www.youtube.com\/c\/KatiaYarnsFabrics\/videos\",\"https:\/\/www.tiktok.com\/@katiacrafts\",\"https:\/\/www.instagram.com\/katiafabrics\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#\/schema\/person\/7f7e1104097c12cdcd6f14538e89f243\",\"name\":\"Marisa Guerrero | Katia Team\",\"description\":\"At Katia, we've been creating yarns for crafts for over 70 years. Each season, we develop new high-quality yarns under the Katia, WOW!, Lanas Stop, and Concept by Katia brands. Inspired by our wide and varied collection of yarns, we also publish knitting and crochet pattern magazines for garments and accessories for Women, Men, Kids, Babies, and Home.\",\"url\":\"https:\/\/www.katia.com\/blog\/it\/author\/nuriacastello\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Katia Workshops nei negozi | 3 nuovi progetti all'uncinetto, maglia e cucito","description":"Tre nuovi Katia Workshop nei negozi! Impara a realizzare all'uncinetto una coperta, ai ferri un top con cappuccio o cucire una blusa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.katia.com\/blog\/it\/katia-workshops-nei-negozi-uncinetto-maglia-cucito\/","og_locale":"it_IT","og_type":"article","og_title":"Katia Workshops nei negozi | 3 nuovi progetti all'uncinetto, maglia e cucito","og_description":"Tre nuovi Katia Workshop nei negozi! Impara a realizzare all'uncinetto una coperta, ai ferri un top con cappuccio o cucire una blusa.","og_url":"https:\/\/www.katia.com\/blog\/it\/katia-workshops-nei-negozi-uncinetto-maglia-cucito\/","og_site_name":"Blog di cucito, uncinetto e lavoro a maglia | Blog di Katia","article_publisher":"https:\/\/www.facebook.com\/KatiaYarns\/","article_published_time":"2022-04-07T04:42:25+00:00","article_modified_time":"2023-06-14T09:29:15+00:00","og_image":[{"width":640,"height":640,"url":"https:\/\/i0.wp.com\/www.katia.com\/blog\/wp-content\/uploads\/2023\/06\/workshops-katia-feat-640x640-7.jpg?fit=640%2C640&ssl=1","type":"image\/jpeg"}],"author":"Marisa Guerrero | Katia Team","twitter_card":"summary_large_image","twitter_creator":"@katiayarns","twitter_site":"@katiayarns","twitter_misc":{"Scritto da":"Marisa Guerrero | Katia Team","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.katia.com\/blog\/it\/katia-workshops-nei-negozi-uncinetto-maglia-cucito\/#article","isPartOf":{"@id":"https:\/\/www.katia.com\/blog\/it\/katia-workshops-nei-negozi-uncinetto-maglia-cucito\/"},"author":{"name":"Marisa Guerrero | Katia Team","@id":"https:\/\/www.katia.com\/blog\/it\/#\/schema\/person\/7f7e1104097c12cdcd6f14538e89f243"},"headline":"Nuovi Katia Workshop nei negozi per imparare a realizzare 3 progetti all\u00b4uncinetto, a maglia e di cucito","datePublished":"2022-04-07T04:42:25+00:00","dateModified":"2023-06-14T09:29:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.katia.com\/blog\/it\/katia-workshops-nei-negozi-uncinetto-maglia-cucito\/"},"wordCount":392,"commentCount":0,"publisher":{"@id":"https:\/\/www.katia.com\/blog\/it\/#organization"},"keywords":["seminari","coperta","Negozi","corsi"],"articleSection":["Moda e Accessori"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.katia.com\/blog\/it\/katia-workshops-nei-negozi-uncinetto-maglia-cucito\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.katia.com\/blog\/it\/katia-workshops-nei-negozi-uncinetto-maglia-cucito\/","url":"https:\/\/www.katia.com\/blog\/it\/katia-workshops-nei-negozi-uncinetto-maglia-cucito\/","name":"Katia Workshops nei negozi | 3 nuovi progetti all'uncinetto, maglia e cucito","isPartOf":{"@id":"https:\/\/www.katia.com\/blog\/it\/#website"},"datePublished":"2022-04-07T04:42:25+00:00","dateModified":"2023-06-14T09:29:15+00:00","description":"Tre nuovi Katia Workshop nei negozi! Impara a realizzare all'uncinetto una coperta, ai ferri un top con cappuccio o cucire una blusa.","breadcrumb":{"@id":"https:\/\/www.katia.com\/blog\/it\/katia-workshops-nei-negozi-uncinetto-maglia-cucito\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.katia.com\/blog\/it\/katia-workshops-nei-negozi-uncinetto-maglia-cucito\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.katia.com\/blog\/it\/katia-workshops-nei-negozi-uncinetto-maglia-cucito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.katia.com\/blog\/it\/"},{"@type":"ListItem","position":2,"name":"Nuovi Katia Workshop nei negozi per imparare a realizzare 3 progetti all\u00b4uncinetto, a maglia e di cucito"}]},{"@type":"WebSite","@id":"https:\/\/www.katia.com\/blog\/it\/#website","url":"https:\/\/www.katia.com\/blog\/it\/","name":"www.katia.com","description":"Il tuo blog di uncinetto, lavoro a maglia, cucito o macram\u00e8 con tutorial per imparare e idee per lavorare e cucire capi unici. Blog di Katia, per spiriti creativi\n","publisher":{"@id":"https:\/\/www.katia.com\/blog\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.katia.com\/blog\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.katia.com\/blog\/it\/#organization","name":"Fil Katia, S.A","url":"https:\/\/www.katia.com\/blog\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.katia.com\/blog\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg","contentUrl":"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg","width":"600","height":"1200","caption":"Fil Katia, S.A"},"image":{"@id":"https:\/\/www.katia.com\/blog\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KatiaYarns\/","https:\/\/twitter.com\/katiayarns","http:\/\/instagram.com\/katiayarns","https:\/\/www.linkedin.com\/company\/fil-katia\/","https:\/\/www.pinterest.com\/KatiaYarns\/","https:\/\/www.youtube.com\/c\/KatiaYarnsFabrics\/videos","https:\/\/www.tiktok.com\/@katiacrafts","https:\/\/www.instagram.com\/katiafabrics"]},{"@type":"Person","@id":"https:\/\/www.katia.com\/blog\/it\/#\/schema\/person\/7f7e1104097c12cdcd6f14538e89f243","name":"Marisa Guerrero | Katia Team","description":"At Katia, we've been creating yarns for crafts for over 70 years. Each season, we develop new high-quality yarns under the Katia, WOW!, Lanas Stop, and Concept by Katia brands. Inspired by our wide and varied collection of yarns, we also publish knitting and crochet pattern magazines for garments and accessories for Women, Men, Kids, Babies, and Home.","url":"https:\/\/www.katia.com\/blog\/it\/author\/nuriacastello\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.katia.com\/blog\/wp-content\/uploads\/2023\/06\/workshops-katia-feat-640x640-7.jpg?fit=640%2C640&ssl=1","jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/peUVQy-15OV","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/posts\/260705"}],"collection":[{"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/comments?post=260705"}],"version-history":[{"count":0,"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/posts\/260705\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/media\/260706"}],"wp:attachment":[{"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/media?parent=260705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/categories?post=260705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/tags?post=260705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}