{"id":12005,"count":112,"description":"Trova modelli esclusivi per lavorare e cucire assieme alle tendenze di filati moda per ogni stagione. Te lo raccontiamo nel blog di Katia.","link":"https:\/\/www.katia.com\/blog\/it\/category\/designer-tendenze\/","name":"Designer e Tendenze","slug":"designer-tendenze","taxonomy":"category","parent":0,"meta":[],"acf":[],"z_taxonomy_image_url":"https:\/\/www.katia.com\/blog\/wp-content\/plugins\/categories-images\/assets\/images\/placeholder.png","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Disegnatori e tendenze su tessuti e filati |Blog di Katia<\/title>\n<meta name=\"description\" content=\"Trova modelli esclusivi per lavorare e cucire assieme alle tendenze di filati moda per ogni stagione. Te lo raccontiamo nel blog di Katia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.katia.com\/blog\/it\/category\/designer-tendenze\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Disegnatori e tendenze su tessuti e filati |Blog di Katia\" \/>\n<meta property=\"og:description\" content=\"Trova modelli esclusivi per lavorare e cucire assieme alle tendenze di filati moda per ogni stagione. Te lo raccontiamo nel blog di Katia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.katia.com\/blog\/it\/category\/designer-tendenze\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog di cucito, uncinetto e lavoro a maglia | Blog di Katia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@katiayarns\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/category\/designer-tendenze\/\",\"url\":\"https:\/\/www.katia.com\/blog\/it\/category\/designer-tendenze\/\",\"name\":\"Disegnatori e tendenze su tessuti e filati |Blog di Katia\",\"isPartOf\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#website\"},\"description\":\"Trova modelli esclusivi per lavorare e cucire assieme alle tendenze di filati moda per ogni stagione. Te lo raccontiamo nel blog di Katia.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/category\/designer-tendenze\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/category\/designer-tendenze\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/www.katia.com\/blog\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Designer e Tendenze\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#website\",\"url\":\"https:\/\/www.katia.com\/blog\/it\/\",\"name\":\"www.katia.com\",\"description\":\"Il tuo blog di uncinetto, lavoro a maglia, cucito o macram\u00e8 con tutorial per imparare e idee per lavorare e cucire capi unici. Blog di Katia, per spiriti creativi\\n\",\"publisher\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.katia.com\/blog\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#organization\",\"name\":\"Fil Katia, S.A\",\"url\":\"https:\/\/www.katia.com\/blog\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg\",\"contentUrl\":\"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg\",\"width\":\"600\",\"height\":\"1200\",\"caption\":\"Fil Katia, S.A\"},\"image\":{\"@id\":\"https:\/\/www.katia.com\/blog\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/KatiaYarns\/\",\"https:\/\/twitter.com\/katiayarns\",\"http:\/\/instagram.com\/katiayarns\",\"https:\/\/www.linkedin.com\/company\/fil-katia\/\",\"https:\/\/www.pinterest.com\/KatiaYarns\/\",\"https:\/\/www.youtube.com\/c\/KatiaYarnsFabrics\/videos\",\"https:\/\/www.tiktok.com\/@katiacrafts\",\"https:\/\/www.instagram.com\/katiafabrics\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Disegnatori e tendenze su tessuti e filati |Blog di Katia","description":"Trova modelli esclusivi per lavorare e cucire assieme alle tendenze di filati moda per ogni stagione. Te lo raccontiamo nel blog di Katia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.katia.com\/blog\/it\/category\/designer-tendenze\/","og_locale":"it_IT","og_type":"article","og_title":"Disegnatori e tendenze su tessuti e filati |Blog di Katia","og_description":"Trova modelli esclusivi per lavorare e cucire assieme alle tendenze di filati moda per ogni stagione. Te lo raccontiamo nel blog di Katia.","og_url":"https:\/\/www.katia.com\/blog\/it\/category\/designer-tendenze\/","og_site_name":"Blog di cucito, uncinetto e lavoro a maglia | Blog di Katia","twitter_card":"summary_large_image","twitter_site":"@katiayarns","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.katia.com\/blog\/it\/category\/designer-tendenze\/","url":"https:\/\/www.katia.com\/blog\/it\/category\/designer-tendenze\/","name":"Disegnatori e tendenze su tessuti e filati |Blog di Katia","isPartOf":{"@id":"https:\/\/www.katia.com\/blog\/it\/#website"},"description":"Trova modelli esclusivi per lavorare e cucire assieme alle tendenze di filati moda per ogni stagione. Te lo raccontiamo nel blog di Katia.","breadcrumb":{"@id":"https:\/\/www.katia.com\/blog\/it\/category\/designer-tendenze\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.katia.com\/blog\/it\/category\/designer-tendenze\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.katia.com\/blog\/it\/"},{"@type":"ListItem","position":2,"name":"Designer e Tendenze"}]},{"@type":"WebSite","@id":"https:\/\/www.katia.com\/blog\/it\/#website","url":"https:\/\/www.katia.com\/blog\/it\/","name":"www.katia.com","description":"Il tuo blog di uncinetto, lavoro a maglia, cucito o macram\u00e8 con tutorial per imparare e idee per lavorare e cucire capi unici. Blog di Katia, per spiriti creativi\n","publisher":{"@id":"https:\/\/www.katia.com\/blog\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.katia.com\/blog\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.katia.com\/blog\/it\/#organization","name":"Fil Katia, S.A","url":"https:\/\/www.katia.com\/blog\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.katia.com\/blog\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg","contentUrl":"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg","width":"600","height":"1200","caption":"Fil Katia, S.A"},"image":{"@id":"https:\/\/www.katia.com\/blog\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KatiaYarns\/","https:\/\/twitter.com\/katiayarns","http:\/\/instagram.com\/katiayarns","https:\/\/www.linkedin.com\/company\/fil-katia\/","https:\/\/www.pinterest.com\/KatiaYarns\/","https:\/\/www.youtube.com\/c\/KatiaYarnsFabrics\/videos","https:\/\/www.tiktok.com\/@katiacrafts","https:\/\/www.instagram.com\/katiafabrics"]}]}},"_links":{"self":[{"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/categories\/12005"}],"collection":[{"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.katia.com\/blog\/it\/wp-json\/wp\/v2\/posts?categories=12005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}