{"id":213377,"date":"2020-01-08T12:30:43","date_gmt":"2020-01-08T11:30:43","guid":{"rendered":"https:\/\/www.katia.com\/blog\/coudre-un-grand-sac-a-projet-tricot\/"},"modified":"2024-03-08T09:29:18","modified_gmt":"2024-03-08T08:29:18","slug":"coudre-un-grand-sac-a-projet-tricot","status":"publish","type":"post","link":"https:\/\/www.katia.com\/blog\/fr\/coudre-un-grand-sac-a-projet-tricot\/","title":{"rendered":"Apprenez \u00e0 coudre ce grand sac \u00e0 projet tricot pour vos aiguilles et crochet dans notre groupe de SAL!"},"content":{"rendered":"<p>Pour toutes et tous les inconditionnels des Laines Katia et de Katia Fabrics, nous vous pr\u00e9sentons le meilleur sac \u00e0 projet qui vous permettra d\u2019organiser vos <strong>laines<\/strong> et vos aiguilles de tricot et <strong>crochets<\/strong>. Participez \u00e0 notre SAL pour coudre ensemble le patron du\u00a0<a href=\"https:\/\/www.katia.com\/FR\/Design-a16--A16-2319.html\" target=\"_blank\" rel=\"noopener noreferrer\">Sac \u00e0 projet + porte-pelote<\/a> , qui, nous en sommes s\u00fbrs, vont beaucoup vous plaire.<\/p>\n<p>Un sac \u00e0 projet o\u00f9 ranger vos aiguilles et crochets dans les <strong>poches lat\u00e9rales<\/strong> et vos laines dans la poche principale. \u00c0 r\u00e9aliser avec nos <a href=\"https:\/\/www.katia.com\/FR\/tissus.html\" target=\"_blank\" rel=\"noopener noreferrer\">tissus de la collection\u00a0Automne-Hiver 2019\/2020<\/a>. Un <strong>projet couture <\/strong><strong>que vous pourrez facilement confectionner gr\u00e2ce \u00e0 nos tutoriels vid\u00e9o.<\/strong> <strong>Tout un d\u00e9fi pour commencer l\u2019ann\u00e9e ensemble dans notre <\/strong><a href=\"https:\/\/www.facebook.com\/groups\/sewalongkatiafabrics\/\" target=\"_blank\" rel=\"noopener noreferrer\">Groupe de Facebook Sew-Along Katia<\/a>. Un projet \u00e0 la fois et utile, qui vous permettra de prendre soin et de ranger votre mat\u00e9riel de tricot. Si vous souhaitez apprendre, passer de bons moments et partager vos progr\u00e8s, rejoignez-nous et participez \u00e0 notre SAL.<\/p>\n<h2>Le meilleur sac \u00e0 projet tricot\u00a0<\/h2>\n<p>Pour coudre ce mod\u00e8le, vous aurez besoin de deux bouts de tissu, de la ouate, 3 fermetures \u00e0 glissi\u00e8re de 45 cm et le patron en papier que vous trouverez \u00e0 \u00e9chelle dans notre boutique <a href=\"https:\/\/www.katia.com\/FR\/Design-a16--A16-2319.html\" target=\"_blank\" rel=\"noopener noreferrer\">online de Katia<\/a>.<\/p>\n<p>Pr\u00e9parez votre machine \u00e0 coudre, parce que c\u00b4est parti!<\/p>\n<p>Pour coudre un projet identique \u00e0 celui que nous vous proposons sur la photo, vous aurez besoin de:<\/p>\n<p>85 cm de Tissu <a href=\"https:\/\/www.katia.com\/FR\/fabric-p22-tissu-garden-lanterns-2101-22.html\" target=\"_blank\" rel=\"noopener noreferrer\">Popeline de Coton Garden Lanterns<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3944\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/fr\/wp-content\/uploads\/Bolsa-de-labores_fr-feat.jpg?resize=762%2C750&#038;ssl=1\" alt=\"SAL couture sac \u00e0 projet tricot\" width=\"762\" height=\"750\" data-recalc-dims=\"1\" \/><\/p>\n<p>Pour coudre avec les tissus que nous avons utilis\u00e9s pour le <strong>tutoriel vid\u00e9o<\/strong>, vous aurez besoin de:<\/p>\n<p><a href=\"https:\/\/www.katia.com\/FR\/fabric-w6-tissu-main-fox-pink-2112-6.html\" target=\"_blank\" rel=\"noopener noreferrer\">Tissu Waterproof Main Fox Pink<\/a><\/p>\n<p><a href=\"https:\/\/www.katia.com\/FR\/fabric-p15-tissu-fox-forest-floor-2101-15.html\" target=\"_blank\" rel=\"noopener noreferrer\">Tissu Popeline Fox Forest Floor<\/a><\/p>\n<p>Mais, si vous pr\u00e9f\u00e9rez assortir vous-m\u00eame d\u2019autres tissus, vous pouvez le faire en choisissant les motifs de la <a href=\"https:\/\/www.katia.com\/FR\/tissus.html?\" target=\"_blank\" rel=\"noopener noreferrer\">Collection Automne-Hiver 2019\/2020<\/a> qui vous plairont le plus.<\/p>\n<h2>Niveau de couture: interm\u00e9diaire<\/h2>\n<p>Dans la pochette de notre patron, vous trouverez toutes les informations n\u00e9cessaires en ce qui concerne le <strong>mat\u00e9riel<\/strong> et les <strong>outils<\/strong> dont vous aurez besoin. En plus, bien s\u00fbr, de toutes les mesures pour la coupe de toutes les pi\u00e8ces du sac et du <strong>porte-pelote<\/strong>. Vous apprendrez ainsi \u00e0 confectionner les <strong>deux pi\u00e8ces de cet ensemble<\/strong> gr\u00e2ce aux explications pas \u00e0 pas en vid\u00e9o durant les prochaines semaines.<\/p>\n<h2>#KatiaSAL<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3943 size-full\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/fr\/wp-content\/uploads\/slide-posts-knitting-Bag-SAL.jpg?resize=1020%2C391&#038;ssl=1\" alt=\"SAL couture sac \u00e0 projet tricot slide\" width=\"1020\" height=\"391\" data-recalc-dims=\"1\" \/><\/p>\n<p>Dans notre <a href=\"https:\/\/www.facebook.com\/groups\/sewalongkatiafabrics\/\" target=\"_blank\" rel=\"noopener noreferrer\">Groupe de Facebook <strong>SAL #Katia<\/strong>SAL<\/a> vous pourrez montrer vos progr\u00e8s et voir ceux des autres couturi\u00e8res. C\u00b4est un point de rencontre pour les <strong>couturi\u00e8res<\/strong> et <strong>couturiers<\/strong> du monde entier. Nous y partagerons, apprendrons et vivrons la magie de la couture toutes et tous ensemble. Nous coudrons le kit complet tout au long des semaines \u00e0 venir. Un kit compos\u00e9 d\u00b4un sac pour ranger vos laines, crochets et aiguilles entre autres. Ainsi qu\u00b4un mini sac pour votre pelote pendant que vous la tricotez ou crochetez, avec un trou pour y passer le fil. Lancez-vous et rejoignez nous!\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour toutes et tous les inconditionnels des Laines Katia et de Katia Fabrics, nous vous pr\u00e9sentons le meilleur sac \u00e0 projet qui vous permettra d\u2019organiser vos laines et vos aiguilles de tricot et crochets. Participez \u00e0 notre SAL pour coudre ensemble le patron du\u00a0Sac \u00e0 projet + porte-pelote , qui, nous en sommes s\u00fbrs, vont&hellip;<\/p>\n","protected":false},"author":7,"featured_media":213378,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[11932,11934,11941,11944,11951],"tags":[8520,8521,8522],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sew Along: Coudre un sac \u00e0 projet tricot avec les tissus Katia Fabrics<\/title>\n<meta name=\"description\" content=\"Cousez avec nous un grand sac \u00e0 projet tricot et un porte-pelote gr\u00e2ce aux tutos vid\u00e9os que nous publierons pendant les semaines \u00e0 venir.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.katia.com\/blog\/fr\/coudre-un-grand-sac-a-projet-tricot\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sew Along: Coudre un sac \u00e0 projet tricot avec les tissus Katia Fabrics\" \/>\n<meta property=\"og:description\" content=\"Cousez avec nous un grand sac \u00e0 projet tricot et un porte-pelote gr\u00e2ce aux tutos vid\u00e9os que nous publierons pendant les semaines \u00e0 venir.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.katia.com\/blog\/fr\/coudre-un-grand-sac-a-projet-tricot\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de couture, crochet et tricot | Blog de Katia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KatiaYarns\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-08T11:30:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-08T08:29:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/wp-content\/uploads\/2023\/06\/Bolsa-de-labores_fr-feat.jpg?fit=762%2C750&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"762\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Emilie Roter | Katia Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@katiayarns\" \/>\n<meta name=\"twitter:site\" content=\"@katiayarns\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emilie Roter | Katia Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.katia.com\/blog\/fr\/coudre-un-grand-sac-a-projet-tricot\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.katia.com\/blog\/fr\/coudre-un-grand-sac-a-projet-tricot\/\"},\"author\":{\"name\":\"Emilie Roter | Katia Team\",\"@id\":\"https:\/\/www.katia.com\/blog\/fr\/#\/schema\/person\/57179398c88db19cf9bac525353b0953\"},\"headline\":\"Apprenez \u00e0 coudre ce grand sac \u00e0 projet tricot pour vos aiguilles et crochet dans notre groupe de SAL!\",\"datePublished\":\"2020-01-08T11:30:43+00:00\",\"dateModified\":\"2024-03-08T08:29:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.katia.com\/blog\/fr\/coudre-un-grand-sac-a-projet-tricot\/\"},\"wordCount\":489,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.katia.com\/blog\/fr\/#organization\"},\"keywords\":[\"SAL\",\"Sac \u00e0 projet\",\"patron couture\"],\"articleSection\":[\"Katia 100% You\",\"Concours\",\"Tutoriels et mod\u00e8les\",\"Couture\",\"Id\u00e9es DIY\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.katia.com\/blog\/fr\/coudre-un-grand-sac-a-projet-tricot\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.katia.com\/blog\/fr\/coudre-un-grand-sac-a-projet-tricot\/\",\"url\":\"https:\/\/www.katia.com\/blog\/fr\/coudre-un-grand-sac-a-projet-tricot\/\",\"name\":\"Sew Along: Coudre un sac \u00e0 projet tricot avec les tissus Katia Fabrics\",\"isPartOf\":{\"@id\":\"https:\/\/www.katia.com\/blog\/fr\/#website\"},\"datePublished\":\"2020-01-08T11:30:43+00:00\",\"dateModified\":\"2024-03-08T08:29:18+00:00\",\"description\":\"Cousez avec nous un grand sac \u00e0 projet tricot et un porte-pelote gr\u00e2ce aux tutos vid\u00e9os que nous publierons pendant les semaines \u00e0 venir.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.katia.com\/blog\/fr\/coudre-un-grand-sac-a-projet-tricot\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.katia.com\/blog\/fr\/coudre-un-grand-sac-a-projet-tricot\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.katia.com\/blog\/fr\/coudre-un-grand-sac-a-projet-tricot\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/www.katia.com\/blog\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apprenez \u00e0 coudre ce grand sac \u00e0 projet tricot pour vos aiguilles et crochet dans notre groupe de SAL!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.katia.com\/blog\/fr\/#website\",\"url\":\"https:\/\/www.katia.com\/blog\/fr\/\",\"name\":\"www.katia.com\",\"description\":\"Votre blog de crochet, tricot, couture et macram\u00e9 avec de nombreux tutoriels pour apprendre de nouvelles techniques ainsi que des id\u00e9es pour tricoter, crocheter et coudre des pi\u00e8ces uniques. Blog de Katia pour esprits cr\u00e9atifs.\\n\",\"publisher\":{\"@id\":\"https:\/\/www.katia.com\/blog\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.katia.com\/blog\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.katia.com\/blog\/fr\/#organization\",\"name\":\"Fil Katia, S.A\",\"url\":\"https:\/\/www.katia.com\/blog\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.katia.com\/blog\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg\",\"contentUrl\":\"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg\",\"width\":\"600\",\"height\":\"1200\",\"caption\":\"Fil Katia, S.A\"},\"image\":{\"@id\":\"https:\/\/www.katia.com\/blog\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/KatiaYarns\/\",\"https:\/\/twitter.com\/katiayarns\",\"http:\/\/instagram.com\/katiayarns\",\"https:\/\/www.linkedin.com\/company\/fil-katia\/\",\"https:\/\/www.pinterest.com\/KatiaYarns\/\",\"https:\/\/www.youtube.com\/c\/KatiaYarnsFabrics\/videos\",\"https:\/\/www.tiktok.com\/@katiacrafts\",\"https:\/\/www.instagram.com\/katiafabrics\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.katia.com\/blog\/fr\/#\/schema\/person\/57179398c88db19cf9bac525353b0953\",\"name\":\"Emilie Roter | Katia Team\",\"description\":\"En Katia creamos hilos y lanas para labores desde hace m\u00e1s de 70 a\u00f1os. Cada temporada desarrollamos nuevos hilos de calidad marca Katia, WOW!, Lanas Stop y Concept by Katia. Inspirados en nuestra amplia y variada colecci\u00f3n de ovillos, tambi\u00e9n publicamos revistas de patrones para tejer prendas y accesorios de Mujer, Hombre, Ni\u00f1os, Beb\u00e9 y Hogar.\",\"sameAs\":[\"https:\/\/www.katia.com\/\"],\"url\":\"https:\/\/www.katia.com\/blog\/fr\/author\/katia-blog\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sew Along: Coudre un sac \u00e0 projet tricot avec les tissus Katia Fabrics","description":"Cousez avec nous un grand sac \u00e0 projet tricot et un porte-pelote gr\u00e2ce aux tutos vid\u00e9os que nous publierons pendant les semaines \u00e0 venir.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.katia.com\/blog\/fr\/coudre-un-grand-sac-a-projet-tricot\/","og_locale":"fr_FR","og_type":"article","og_title":"Sew Along: Coudre un sac \u00e0 projet tricot avec les tissus Katia Fabrics","og_description":"Cousez avec nous un grand sac \u00e0 projet tricot et un porte-pelote gr\u00e2ce aux tutos vid\u00e9os que nous publierons pendant les semaines \u00e0 venir.","og_url":"https:\/\/www.katia.com\/blog\/fr\/coudre-un-grand-sac-a-projet-tricot\/","og_site_name":"Blog de couture, crochet et tricot | Blog de Katia","article_publisher":"https:\/\/www.facebook.com\/KatiaYarns\/","article_published_time":"2020-01-08T11:30:43+00:00","article_modified_time":"2024-03-08T08:29:18+00:00","og_image":[{"width":762,"height":750,"url":"https:\/\/i0.wp.com\/www.katia.com\/blog\/wp-content\/uploads\/2023\/06\/Bolsa-de-labores_fr-feat.jpg?fit=762%2C750&ssl=1","type":"image\/jpeg"}],"author":"Emilie Roter | Katia Team","twitter_card":"summary_large_image","twitter_creator":"@katiayarns","twitter_site":"@katiayarns","twitter_misc":{"\u00c9crit par":"Emilie Roter | Katia Team","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.katia.com\/blog\/fr\/coudre-un-grand-sac-a-projet-tricot\/#article","isPartOf":{"@id":"https:\/\/www.katia.com\/blog\/fr\/coudre-un-grand-sac-a-projet-tricot\/"},"author":{"name":"Emilie Roter | Katia Team","@id":"https:\/\/www.katia.com\/blog\/fr\/#\/schema\/person\/57179398c88db19cf9bac525353b0953"},"headline":"Apprenez \u00e0 coudre ce grand sac \u00e0 projet tricot pour vos aiguilles et crochet dans notre groupe de SAL!","datePublished":"2020-01-08T11:30:43+00:00","dateModified":"2024-03-08T08:29:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.katia.com\/blog\/fr\/coudre-un-grand-sac-a-projet-tricot\/"},"wordCount":489,"commentCount":0,"publisher":{"@id":"https:\/\/www.katia.com\/blog\/fr\/#organization"},"keywords":["SAL","Sac \u00e0 projet","patron couture"],"articleSection":["Katia 100% You","Concours","Tutoriels et mod\u00e8les","Couture","Id\u00e9es DIY"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.katia.com\/blog\/fr\/coudre-un-grand-sac-a-projet-tricot\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.katia.com\/blog\/fr\/coudre-un-grand-sac-a-projet-tricot\/","url":"https:\/\/www.katia.com\/blog\/fr\/coudre-un-grand-sac-a-projet-tricot\/","name":"Sew Along: Coudre un sac \u00e0 projet tricot avec les tissus Katia Fabrics","isPartOf":{"@id":"https:\/\/www.katia.com\/blog\/fr\/#website"},"datePublished":"2020-01-08T11:30:43+00:00","dateModified":"2024-03-08T08:29:18+00:00","description":"Cousez avec nous un grand sac \u00e0 projet tricot et un porte-pelote gr\u00e2ce aux tutos vid\u00e9os que nous publierons pendant les semaines \u00e0 venir.","breadcrumb":{"@id":"https:\/\/www.katia.com\/blog\/fr\/coudre-un-grand-sac-a-projet-tricot\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.katia.com\/blog\/fr\/coudre-un-grand-sac-a-projet-tricot\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.katia.com\/blog\/fr\/coudre-un-grand-sac-a-projet-tricot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.katia.com\/blog\/fr\/"},{"@type":"ListItem","position":2,"name":"Apprenez \u00e0 coudre ce grand sac \u00e0 projet tricot pour vos aiguilles et crochet dans notre groupe de SAL!"}]},{"@type":"WebSite","@id":"https:\/\/www.katia.com\/blog\/fr\/#website","url":"https:\/\/www.katia.com\/blog\/fr\/","name":"www.katia.com","description":"Votre blog de crochet, tricot, couture et macram\u00e9 avec de nombreux tutoriels pour apprendre de nouvelles techniques ainsi que des id\u00e9es pour tricoter, crocheter et coudre des pi\u00e8ces uniques. Blog de Katia pour esprits cr\u00e9atifs.\n","publisher":{"@id":"https:\/\/www.katia.com\/blog\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.katia.com\/blog\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.katia.com\/blog\/fr\/#organization","name":"Fil Katia, S.A","url":"https:\/\/www.katia.com\/blog\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.katia.com\/blog\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg","contentUrl":"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg","width":"600","height":"1200","caption":"Fil Katia, S.A"},"image":{"@id":"https:\/\/www.katia.com\/blog\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KatiaYarns\/","https:\/\/twitter.com\/katiayarns","http:\/\/instagram.com\/katiayarns","https:\/\/www.linkedin.com\/company\/fil-katia\/","https:\/\/www.pinterest.com\/KatiaYarns\/","https:\/\/www.youtube.com\/c\/KatiaYarnsFabrics\/videos","https:\/\/www.tiktok.com\/@katiacrafts","https:\/\/www.instagram.com\/katiafabrics"]},{"@type":"Person","@id":"https:\/\/www.katia.com\/blog\/fr\/#\/schema\/person\/57179398c88db19cf9bac525353b0953","name":"Emilie Roter | Katia Team","description":"En Katia creamos hilos y lanas para labores desde hace m\u00e1s de 70 a\u00f1os. Cada temporada desarrollamos nuevos hilos de calidad marca Katia, WOW!, Lanas Stop y Concept by Katia. Inspirados en nuestra amplia y variada colecci\u00f3n de ovillos, tambi\u00e9n publicamos revistas de patrones para tejer prendas y accesorios de Mujer, Hombre, Ni\u00f1os, Beb\u00e9 y Hogar.","sameAs":["https:\/\/www.katia.com\/"],"url":"https:\/\/www.katia.com\/blog\/fr\/author\/katia-blog\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.katia.com\/blog\/wp-content\/uploads\/2023\/06\/Bolsa-de-labores_fr-feat.jpg?fit=762%2C750&ssl=1","jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/peUVQy-Tvz","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.katia.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/213377"}],"collection":[{"href":"https:\/\/www.katia.com\/blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.katia.com\/blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.katia.com\/blog\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.katia.com\/blog\/fr\/wp-json\/wp\/v2\/comments?post=213377"}],"version-history":[{"count":1,"href":"https:\/\/www.katia.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/213377\/revisions"}],"predecessor-version":[{"id":298593,"href":"https:\/\/www.katia.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/213377\/revisions\/298593"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.katia.com\/blog\/fr\/wp-json\/wp\/v2\/media\/213378"}],"wp:attachment":[{"href":"https:\/\/www.katia.com\/blog\/fr\/wp-json\/wp\/v2\/media?parent=213377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.katia.com\/blog\/fr\/wp-json\/wp\/v2\/categories?post=213377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.katia.com\/blog\/fr\/wp-json\/wp\/v2\/tags?post=213377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}