{"id":77633,"date":"2020-08-12T09:25:29","date_gmt":"2020-08-12T07:25:29","guid":{"rendered":"https:\/\/www.katia.com\/blog\/video-tutorial-chal-atlantico-a-dos-agujas-de-punto\/"},"modified":"2023-06-01T11:54:52","modified_gmt":"2023-06-01T09:54:52","slug":"video-tutorial-chal-atlantico-a-dos-agujas-de-punto","status":"publish","type":"post","link":"https:\/\/www.katia.com\/blog\/es\/video-tutorial-chal-atlantico-a-dos-agujas-de-punto\/","title":{"rendered":"V\u00eddeo tutorial Chal Atl\u00e1ntico de Marianela Galo: C\u00f3mo tejer un chal de media luna para las noches de verano"},"content":{"rendered":"<p>\u00a1Hola! Me llamo <a href=\"https:\/\/marianelagalo.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Marianela Galo<\/a> y soy dise\u00f1adora de <em>g\u00e9nero de punto.<\/em> Desde mi adolescencia, <strong>tejer<\/strong> es mi momento del d\u00eda de descanso, <em>creatividad<\/em> y<strong> meditaci\u00f3n<\/strong>. Como todas las mujeres en mi familia, siempre tengo alg\u00fan proyecto entre manos que me ilusiona. Con el tiempo he llegado a dedicarme al dise\u00f1o profesionalmente. \u00a1Soy feliz con lo que hago! La mayor\u00eda de mis creaciones est\u00e1n inspiradas en lugares del mundo o a partir de lo que me transmite un material. Como este<em> Chal Atl\u00e1ntico<\/em> tejido con <a href=\"https:\/\/www.katia.com\/ES\/lanas-estambres-primavera-verano-veganette-1183.html\" target=\"_blank\" rel=\"noopener noreferrer\">Katia <em>Veganette<\/em>,<\/a> un dise\u00f1o exclusivo para ti. Sigue el <b>patr\u00f3n de punto <\/b>y el <strong>v\u00eddeo<\/strong> <em>tutorial<\/em> Chal Atl\u00e1ntico para tejer un <em>accesorio<\/em> perfecto para las noches frescas. \u00a1Espero que lo disfrutes! Te invito a descubrir mi trabajo en <a href=\"https:\/\/www.instagram.com\/marianelagalo\/\" target=\"_blank\" rel=\"noopener noreferrer\">Instagram<\/a>, <a href=\"https:\/\/www.ravelry.com\/designers\/marianela-galo\" target=\"_blank\" rel=\"noopener noreferrer\">Ravelry<\/a>, <a href=\"https:\/\/www.facebook.com\/Knitestejer\/\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook<\/a> y en Youtube <strong><a href=\"https:\/\/www.youtube.com\/channel\/UC7r4XaV9gQoEre0sMAaah4Q\" target=\"_blank\" rel=\"noopener noreferrer\">Knit es Tejer<\/a><\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-12637\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/es\/wp-content\/uploads\/2020\/07\/knit-es-tejer-atlantico-shawl-pattern-SLIDE.jpg?resize=1020%2C391&#038;ssl=1\" alt=\"V\u00eddeo tutorial Chal Atl\u00e1ntico \" width=\"1020\" height=\"391\" data-recalc-dims=\"1\" \/><\/p>\n<h2>V\u00eddeo tutorial<strong>\u00a0<em>Chal Atl\u00e1ntico<\/em><\/strong><\/h2>\n<p>Este chal est\u00e1 inspirado en el Atl\u00e1ntico, un oc\u00e9ano de aguas fr\u00edas y grandes corrientes. El chal Atl\u00e1ntico es muy <strong>f\u00e1cil de tejer<\/strong>, con una estructura muy original en forma de <em>media luna<\/em>. Adem\u00e1s de 3 l\u00edneas de <em>aumentos<\/em> que recorren el cuerpo del chal llevando la mirada a las orillas del oc\u00e9ano. En el siguiente<strong> video tutorial<\/strong> Chal Atl\u00e1ntico te muestro una primera secci\u00f3n inspirada en la amplitud del <em>oc\u00e9ano<\/em>, y una segunda secci\u00f3n que se inspira en las <em>orillas<\/em> del mar y la <em>playa<\/em>. Para terminar, en el <strong>borde<\/strong> del chal he a\u00f1adido <em>ondas verticales<\/em> como si fuera la llegada de sus aguas a la orilla de la playa.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/saNCB72JAiQ\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h2><strong>Patr\u00f3n de <em>Knit es Tejer<\/em><\/strong><\/h2>\n<p><strong>Materiales: <\/strong><a href=\"https:\/\/www.katia.com\/ES\/lanas-estambres-primavera-verano-veganette-1183.html\" target=\"_blank\" rel=\"noopener noreferrer\">4 ovillos Katia Veganette<\/a> col.107, <a href=\"https:\/\/www.katia.com\/ES\/agujas-y-ganchillos.html?tipo_ac%5B%5D=AGUJAS-CIRCULARES\" target=\"_blank\" rel=\"noopener noreferrer\">agujas circulares de 4,5mm<\/a> con cable de 80cm, 2 marcadores, tijeras y aguja lanera.<\/p>\n<p><strong>Muestra <\/strong>10x10cm: 16,5 puntos x 25 vueltas\u00a0en <em>punto jersey derecho<\/em><\/p>\n<p><strong>Medidas<\/strong><\/p>\n<ul>\n<li>Largo:\u00a0190 cm<\/li>\n<li>Ancho: 47 cm<\/li>\n<\/ul>\n<h3><strong>Puntos utilizados\u00a0<\/strong><\/h3>\n<ul>\n<li><strong>2pjd\u00a0<\/strong>\u2013 dos puntos juntos del derecho<\/li>\n<li><strong>2pjdr\u00a0<\/strong>\u2013 dos puntos juntos del derecho\u00a0retorcidos<\/li>\n<li><strong>D<\/strong>\u00a0\u2013 derecho de la labor<\/li>\n<li><strong>deslm<\/strong>\u00a0\u2013 deslizar marcador<\/li>\n<li><strong>dism<\/strong>\u00a0\u2013 disminuci\u00f3n o\u00a0surjete\u00a0simple<\/li>\n<li><strong>h<\/strong>\u00a0\u2013 echar hebra<\/li>\n<li><strong>p<\/strong>\u00a0\u2013 punto(s)<\/li>\n<li><strong>pd<\/strong>\u00a0\u2013 punto derecho<\/li>\n<li><strong>pm<\/strong>\u00a0\u2013 poner marcador<\/li>\n<li><strong>pr<\/strong>\u00a0\u2013 punto rev\u00e9s<\/li>\n<li><strong>R<\/strong>\u00a0\u2013 rev\u00e9s de la labor<\/li>\n<li><strong>rep<\/strong>\u00a0&#8211; repetir<\/li>\n<li><strong>vta(s)<\/strong>\u00a0\u2013 vuelta(s)<\/li>\n<\/ul>\n<h3><strong>Notas<\/strong><\/h3>\n<ul>\n<li>El chal consta de 2 secciones: la secci\u00f3n 1 es el Oc\u00e9ano y la secci\u00f3n 2, la Orilla del Mar.<\/li>\n<li>Se trabaja en pasadas de<em> ida y vuelta<\/em>. Comprobar al inicio de cada secci\u00f3n si comienza con una vta\u00a0en el D o el R.<\/li>\n<li>En la secci\u00f3n 1,\u00a0deslm\u00a0seg\u00fan se\u00a0trabaja en las\u00a0vtas\u00a0donde no est\u00e1 indicado expresamente.<\/li>\n<\/ul>\n<h3><strong>Inicio<\/strong><\/h3>\n<p><strong>Solapa de punto bobo:\u00a0<\/strong>montar 3p, trabajar 6vtas\u00a0pd, girar 90 grados la labor, recoger y trabajar 3pd del lateral izquierdo, girar de nuevo 90 grados, recoger y trabajar 3pd del montaje (9p).<\/p>\n<p><strong>V1(R):<\/strong>\u00a03pd, h, 3pr, h, 3pd\u00a0(11p).<\/p>\n<p><strong>V2(D):<\/strong>\u00a03pd, h, 2pd,\u00a0pm, 1pd,\u00a0pm, 2pd, h, 3pd\u00a0(13p).<\/p>\n<p><strong>V3(R):<\/strong>\u00a03pd, h,\u00a0pr\u00a0hasta\u00a03p antes del final, h, 3pd. Al mismo\u00a0tiempo\u00a0deslm\u00a0(15p).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-12638\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/es\/wp-content\/uploads\/2020\/07\/knit-es-tejer-atlantico-shawl-pattern-2.jpg?resize=924%2C690&#038;ssl=1\" alt=\"V\u00eddeo tutorial Chal Atl\u00e1ntico\" width=\"924\" height=\"690\" data-recalc-dims=\"1\" \/><\/p>\n<h2><strong>Secci\u00f3n 1: Oc\u00e9ano<\/strong><\/h2>\n<p><strong>V de preparaci\u00f3n\u00a0(D):<\/strong>\u00a03pd, h, 2pd, h, 2pd, h,\u00a0deslm, 1pd,\u00a0deslm, h, 2pd, h, 2pd, h, 3pd.<\/p>\n<p><strong>V1(R):<\/strong>\u00a03pd, h,\u00a0pr\u00a0hasta\u00a0que queden\u00a03p, h, 3pd.<\/p>\n<p><strong>V2:<\/strong>\u00a03pd, h,\u00a0pd\u00a0hasta 3p antes del final, h, 3pd.<\/p>\n<p><strong>V3:<\/strong>\u00a0rep\u00a0<strong>V1<\/strong>.<\/p>\n<p><strong>V4:<\/strong>\u00a03pd, h,\u00a0pd\u00a0hasta la mitad de tramo, h,\u00a0pd\u00a0hasta el marcador, h,\u00a0deslm,\u00a01pd,\u00a0deslm,\u00a0h,\u00a0pd\u00a0hasta la mitad de tramo, h,\u00a0pd\u00a0hasta\u00a0que queden\u00a03p, h, 3pd.\u00a0<strong>(Ver v\u00eddeo)<\/strong><\/p>\n<p>Rep\u00a0<strong>V1-V4<\/strong>\u00a0acabando en una\u00a0<strong>V3\u00a0<\/strong>hasta tener 279p.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-12636\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/es\/wp-content\/uploads\/2020\/07\/knit-es-tejer-atlantico-shawl-pattern.jpg?resize=768%2C690&#038;ssl=1\" alt=\"V\u00eddeo tutorial Chal Atl\u00e1ntico \" width=\"768\" height=\"690\" data-recalc-dims=\"1\" \/><\/p>\n<h2><strong>Secci\u00f3n 2: Orilla del mar<\/strong><\/h2>\n<p><strong>V1(D):<\/strong>\u00a03pd, h, 4pd, *dism, 2pd, h, 2pd*,\u00a0rep\u00a0**\u00a0hasta\u00a0que queden\u00a08p, 5pd, h, 3pd.\u00a0Al\u00a0mismo tiempo, quitar los marcadores.<\/p>\n<p><strong>V2\u00a0y todas las\u00a0vtas\u00a0pares hasta la V28(R):<\/strong>\u00a03pd, h,\u00a0pr\u00a0hasta\u00a0que queden 3p,\u00a0h, 3pd.<\/p>\n<p><strong>V3<\/strong>:\u00a03pd, h, 6pd, *dism, 2pd, h, 2pd\u00a0*,\u00a0rep\u00a0**\u00a0hasta\u00a0que queden\u00a04p, 1pd, h, 3pd.<\/p>\n<p><strong>V5<\/strong>:\u00a03pd, h, 2pd, *dism, 2pd, h, 2pd\u00a0*,\u00a0rep\u00a0**\u00a0hasta\u00a0que queden\u00a06p, 3pd, h, 3pd.<\/p>\n<p><strong>V7<\/strong>: 3pd, h, 3pd, *2pjd, 2pd, h, 2pd\u00a0*,\u00a0rep\u00a0**\u00a0hasta\u00a0que queden\u00a03p, h, 3pd.<\/p>\n<p><strong>V9<\/strong>: 3pd, h, 4pd, *2pjd, 2pd, h, 2pd\u00a0*,\u00a0rep\u00a0**\u00a0hasta\u00a0que queden\u00a06p, 3pd, h, 3pd.<\/p>\n<p><strong>V11<\/strong>: 3pd, h, 5pd, *2pjd, 2pd, h, 2pd\u00a0*,\u00a0rep\u00a0**\u00a0hasta\u00a0que queden\u00a03p, h, 3pd.<\/p>\n<p><strong>V13<\/strong>:\u00a03pd, h, 1pd, *dism, 2pd, h, 2pd\u00a0*,\u00a0rep\u00a0**\u00a0hasta\u00a0que queden\u00a05p, 2pd, h, 3pd.<\/p>\n<p><strong>V15<\/strong>:\u00a03pd, h, 3pd, *dism, 2pd, h, 2pd\u00a0*,\u00a0rep\u00a0**\u00a0hasta\u00a0que queden\u00a07p, 4pd, h, 3pd.<\/p>\n<p><strong>V17<\/strong>: 3pd, h, 5pd, *dism, 2pd, h, 2pd\u00a0*,\u00a0rep\u00a0**\u00a0hasta\u00a0que queden\u00a03p, h, 3pd.<\/p>\n<p><strong>V19<\/strong>: 3pd, h, 6pd, *2pjd, 2pd, h, 2pd\u00a0*,\u00a0rep\u00a0**\u00a0hasta\u00a0que queden\u00a06p, 3pd, h, 3pd.<\/p>\n<p><strong>V21<\/strong>:\u00a03pd, h, 1pd, *2pjd, 2pd, h, 2pd\u00a0*,\u00a0rep\u00a0**\u00a0hasta\u00a0que queden\u00a03p, h, 3pd.<\/p>\n<p><strong>V23<\/strong>: 3pd, h, 2pd, *2pjd, 2pd, h, 2pd\u00a0*,\u00a0rep\u00a0**\u00a0hasta\u00a0que queden\u00a06p, 3pd, h, 3pd.<\/p>\n<p><strong>V25<\/strong>: 3pd, h, 4pd, *dism, 2pd, h, 2pd\u00a0*,\u00a0rep\u00a0**\u00a0hasta\u00a0que queden\u00a08p, 5pd, h, 3pd.<\/p>\n<p><strong>V27<\/strong>: 3pd, h, 6pd, *dism, 2pd, h, 2pd\u00a0*,\u00a0rep\u00a0**\u00a0hasta\u00a0que queden\u00a010p,\u00a07pd, h, 3pd.<\/p>\n<p><strong>V29<\/strong>: 3pd, h, 8pd, *dism, 2pd, h, 2pd\u00a0*,\u00a0rep\u00a0**\u00a0hasta\u00a0que queden\u00a012p,\u00a09pd, h, 3pd.<\/p>\n<p><strong>V30<\/strong>: 3pd,\u00a0pr\u00a0hasta\u00a0que queden\u00a03p, 3pd.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-12639\" src=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/es\/wp-content\/uploads\/2020\/07\/knit-es-tejer-atlantico-shawl-pattern-3.jpg?resize=924%2C690&#038;ssl=1\" alt=\"chal de punto media luna\" width=\"924\" height=\"690\" data-recalc-dims=\"1\" \/><\/p>\n<h3><strong>Cierre el\u00e1stico<\/strong><\/h3>\n<p>2pd,\u00a0devolverlos a la aguja izquierda, 2pjdr, *1pd,\u00a0devolver 2p\u00a0a la aguja izquierda, 2pjdr\u00a0*,\u00a0rep\u00a0** hasta cerrar todos los p.<\/p>\n<h3><strong>Remates<\/strong><\/h3>\n<p>Esconder los hilos y <strong>bloquear<\/strong> el chal.<\/p>\n<h2>Sorteo para tejer el Chal Atl\u00e1ntico<\/h2>\n<p>\u00bfQuieres tejer el Chal Atl\u00e1ntico durante las vacaciones? Sigue a <a href=\"https:\/\/www.instagram.com\/marianelagalo\/\">@marianelagalo<\/a> para no perderte el pr\u00f3ximo sorteo de ovillos Katia Veganette para tejer el Chal Atl\u00e1ntico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Hola! Me llamo Marianela Galo y soy dise\u00f1adora de g\u00e9nero de punto. Desde mi adolescencia, tejer es mi momento del d\u00eda de descanso, creatividad y meditaci\u00f3n. Como todas las mujeres en mi familia, siempre tengo alg\u00fan proyecto entre manos que me ilusiona. Con el tiempo he llegado a dedicarme al dise\u00f1o profesionalmente. \u00a1Soy feliz con&hellip;<\/p>\n","protected":false},"author":2,"featured_media":138359,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[11892,11887,11903,11889,11891,11893],"tags":[1057,2763,4247,4248,4249],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>V\u00eddeo tutorial Chal Atl\u00e1ntico: teje a dos agujas un accesorio refrescante<\/title>\n<meta name=\"description\" content=\"Sigue el patr\u00f3n de punto y el v\u00eddeo tutorial Chal Atl\u00e1ntico para tejer un accesorio perfecto para las noches frescas. \u00a1Espero que lo disfrutes!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.katia.com\/blog\/es\/video-tutorial-chal-atlantico-a-dos-agujas-de-punto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"V\u00eddeo tutorial Chal Atl\u00e1ntico: teje a dos agujas un accesorio refrescante\" \/>\n<meta property=\"og:description\" content=\"Sigue el patr\u00f3n de punto y el v\u00eddeo tutorial Chal Atl\u00e1ntico para tejer un accesorio perfecto para las noches frescas. \u00a1Espero que lo disfrutes!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.katia.com\/blog\/es\/video-tutorial-chal-atlantico-a-dos-agujas-de-punto\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de costura, ganchillo y punto | Blog de Katia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KatiaYarns\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-12T07:25:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-01T09:54:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.katia.com\/blog\/wp-content\/uploads\/2023\/05\/knit-es-tejer-atlantico-shawl-pattern-2-3.jpg?fit=924%2C690&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"924\" \/>\n\t<meta property=\"og:image:height\" content=\"690\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marisa Guerrero | Katia Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@katiayarns\" \/>\n<meta name=\"twitter:site\" content=\"@katiayarns\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marisa Guerrero | Katia Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.katia.com\/blog\/es\/video-tutorial-chal-atlantico-a-dos-agujas-de-punto\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.katia.com\/blog\/es\/video-tutorial-chal-atlantico-a-dos-agujas-de-punto\/\"},\"author\":{\"name\":\"Marisa Guerrero | Katia Team\",\"@id\":\"https:\/\/www.katia.com\/blog\/es\/#\/schema\/person\/7f7e1104097c12cdcd6f14538e89f243\"},\"headline\":\"V\u00eddeo tutorial Chal Atl\u00e1ntico de Marianela Galo: C\u00f3mo tejer un chal de media luna para las noches de verano\",\"datePublished\":\"2020-08-12T07:25:29+00:00\",\"dateModified\":\"2023-06-01T09:54:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.katia.com\/blog\/es\/video-tutorial-chal-atlantico-a-dos-agujas-de-punto\/\"},\"wordCount\":964,\"commentCount\":38,\"publisher\":{\"@id\":\"https:\/\/www.katia.com\/blog\/es\/#organization\"},\"keywords\":[\"chales\",\"v\u00eddeos\",\"media luna\",\"ondas verticales\",\"borde\"],\"articleSection\":[\"Punto\",\"Craft Lovers\",\"Moda y complementos\",\"Tendencias Primavera Verano\",\"Tutoriales y patrones\",\"Agujas circulares\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.katia.com\/blog\/es\/video-tutorial-chal-atlantico-a-dos-agujas-de-punto\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.katia.com\/blog\/es\/video-tutorial-chal-atlantico-a-dos-agujas-de-punto\/\",\"url\":\"https:\/\/www.katia.com\/blog\/es\/video-tutorial-chal-atlantico-a-dos-agujas-de-punto\/\",\"name\":\"V\u00eddeo tutorial Chal Atl\u00e1ntico: teje a dos agujas un accesorio refrescante\",\"isPartOf\":{\"@id\":\"https:\/\/www.katia.com\/blog\/es\/#website\"},\"datePublished\":\"2020-08-12T07:25:29+00:00\",\"dateModified\":\"2023-06-01T09:54:52+00:00\",\"description\":\"Sigue el patr\u00f3n de punto y el v\u00eddeo tutorial Chal Atl\u00e1ntico para tejer un accesorio perfecto para las noches frescas. \u00a1Espero que lo disfrutes!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.katia.com\/blog\/es\/video-tutorial-chal-atlantico-a-dos-agujas-de-punto\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.katia.com\/blog\/es\/video-tutorial-chal-atlantico-a-dos-agujas-de-punto\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.katia.com\/blog\/es\/video-tutorial-chal-atlantico-a-dos-agujas-de-punto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/www.katia.com\/blog\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"V\u00eddeo tutorial Chal Atl\u00e1ntico de Marianela Galo: C\u00f3mo tejer un chal de media luna para las noches de verano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.katia.com\/blog\/es\/#website\",\"url\":\"https:\/\/www.katia.com\/blog\/es\/\",\"name\":\"www.katia.com\",\"description\":\"Tu blog de crochet, punto, costura o macram\u00e9 con tutoriales para aprender e ideas para tejer y coser piezas \u00fanicas. Blog de Katia, para esp\u00edritus creativos.\",\"publisher\":{\"@id\":\"https:\/\/www.katia.com\/blog\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.katia.com\/blog\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.katia.com\/blog\/es\/#organization\",\"name\":\"Fil Katia, S.A\",\"url\":\"https:\/\/www.katia.com\/blog\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.katia.com\/blog\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg\",\"contentUrl\":\"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg\",\"width\":\"600\",\"height\":\"1200\",\"caption\":\"Fil Katia, S.A\"},\"image\":{\"@id\":\"https:\/\/www.katia.com\/blog\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/KatiaYarns\/\",\"https:\/\/twitter.com\/katiayarns\",\"http:\/\/instagram.com\/katiayarns\",\"https:\/\/www.linkedin.com\/company\/fil-katia\/\",\"https:\/\/www.pinterest.com\/KatiaYarns\/\",\"https:\/\/www.youtube.com\/c\/KatiaYarnsFabrics\/videos\",\"https:\/\/www.tiktok.com\/@katiacrafts\",\"https:\/\/www.instagram.com\/katiafabrics\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.katia.com\/blog\/es\/#\/schema\/person\/7f7e1104097c12cdcd6f14538e89f243\",\"name\":\"Marisa Guerrero | Katia Team\",\"description\":\"At Katia, we've been creating yarns for crafts for over 70 years. Each season, we develop new high-quality yarns under the Katia, WOW!, Lanas Stop, and Concept by Katia brands. Inspired by our wide and varied collection of yarns, we also publish knitting and crochet pattern magazines for garments and accessories for Women, Men, Kids, Babies, and Home.\",\"url\":\"https:\/\/www.katia.com\/blog\/es\/author\/nuriacastello\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"V\u00eddeo tutorial Chal Atl\u00e1ntico: teje a dos agujas un accesorio refrescante","description":"Sigue el patr\u00f3n de punto y el v\u00eddeo tutorial Chal Atl\u00e1ntico para tejer un accesorio perfecto para las noches frescas. \u00a1Espero que lo disfrutes!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.katia.com\/blog\/es\/video-tutorial-chal-atlantico-a-dos-agujas-de-punto\/","og_locale":"es_ES","og_type":"article","og_title":"V\u00eddeo tutorial Chal Atl\u00e1ntico: teje a dos agujas un accesorio refrescante","og_description":"Sigue el patr\u00f3n de punto y el v\u00eddeo tutorial Chal Atl\u00e1ntico para tejer un accesorio perfecto para las noches frescas. \u00a1Espero que lo disfrutes!","og_url":"https:\/\/www.katia.com\/blog\/es\/video-tutorial-chal-atlantico-a-dos-agujas-de-punto\/","og_site_name":"Blog de costura, ganchillo y punto | Blog de Katia","article_publisher":"https:\/\/www.facebook.com\/KatiaYarns\/","article_published_time":"2020-08-12T07:25:29+00:00","article_modified_time":"2023-06-01T09:54:52+00:00","og_image":[{"width":924,"height":690,"url":"https:\/\/i0.wp.com\/www.katia.com\/blog\/wp-content\/uploads\/2023\/05\/knit-es-tejer-atlantico-shawl-pattern-2-3.jpg?fit=924%2C690&ssl=1","type":"image\/jpeg"}],"author":"Marisa Guerrero | Katia Team","twitter_card":"summary_large_image","twitter_creator":"@katiayarns","twitter_site":"@katiayarns","twitter_misc":{"Escrito por":"Marisa Guerrero | Katia Team","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.katia.com\/blog\/es\/video-tutorial-chal-atlantico-a-dos-agujas-de-punto\/#article","isPartOf":{"@id":"https:\/\/www.katia.com\/blog\/es\/video-tutorial-chal-atlantico-a-dos-agujas-de-punto\/"},"author":{"name":"Marisa Guerrero | Katia Team","@id":"https:\/\/www.katia.com\/blog\/es\/#\/schema\/person\/7f7e1104097c12cdcd6f14538e89f243"},"headline":"V\u00eddeo tutorial Chal Atl\u00e1ntico de Marianela Galo: C\u00f3mo tejer un chal de media luna para las noches de verano","datePublished":"2020-08-12T07:25:29+00:00","dateModified":"2023-06-01T09:54:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.katia.com\/blog\/es\/video-tutorial-chal-atlantico-a-dos-agujas-de-punto\/"},"wordCount":964,"commentCount":38,"publisher":{"@id":"https:\/\/www.katia.com\/blog\/es\/#organization"},"keywords":["chales","v\u00eddeos","media luna","ondas verticales","borde"],"articleSection":["Punto","Craft Lovers","Moda y complementos","Tendencias Primavera Verano","Tutoriales y patrones","Agujas circulares"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.katia.com\/blog\/es\/video-tutorial-chal-atlantico-a-dos-agujas-de-punto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.katia.com\/blog\/es\/video-tutorial-chal-atlantico-a-dos-agujas-de-punto\/","url":"https:\/\/www.katia.com\/blog\/es\/video-tutorial-chal-atlantico-a-dos-agujas-de-punto\/","name":"V\u00eddeo tutorial Chal Atl\u00e1ntico: teje a dos agujas un accesorio refrescante","isPartOf":{"@id":"https:\/\/www.katia.com\/blog\/es\/#website"},"datePublished":"2020-08-12T07:25:29+00:00","dateModified":"2023-06-01T09:54:52+00:00","description":"Sigue el patr\u00f3n de punto y el v\u00eddeo tutorial Chal Atl\u00e1ntico para tejer un accesorio perfecto para las noches frescas. \u00a1Espero que lo disfrutes!","breadcrumb":{"@id":"https:\/\/www.katia.com\/blog\/es\/video-tutorial-chal-atlantico-a-dos-agujas-de-punto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.katia.com\/blog\/es\/video-tutorial-chal-atlantico-a-dos-agujas-de-punto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.katia.com\/blog\/es\/video-tutorial-chal-atlantico-a-dos-agujas-de-punto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.katia.com\/blog\/es\/"},{"@type":"ListItem","position":2,"name":"V\u00eddeo tutorial Chal Atl\u00e1ntico de Marianela Galo: C\u00f3mo tejer un chal de media luna para las noches de verano"}]},{"@type":"WebSite","@id":"https:\/\/www.katia.com\/blog\/es\/#website","url":"https:\/\/www.katia.com\/blog\/es\/","name":"www.katia.com","description":"Tu blog de crochet, punto, costura o macram\u00e9 con tutoriales para aprender e ideas para tejer y coser piezas \u00fanicas. Blog de Katia, para esp\u00edritus creativos.","publisher":{"@id":"https:\/\/www.katia.com\/blog\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.katia.com\/blog\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.katia.com\/blog\/es\/#organization","name":"Fil Katia, S.A","url":"https:\/\/www.katia.com\/blog\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.katia.com\/blog\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg","contentUrl":"https:\/\/www.katia.com\/blog\/wp-content\/uploads\/2016\/12\/logo_katia.svg","width":"600","height":"1200","caption":"Fil Katia, S.A"},"image":{"@id":"https:\/\/www.katia.com\/blog\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KatiaYarns\/","https:\/\/twitter.com\/katiayarns","http:\/\/instagram.com\/katiayarns","https:\/\/www.linkedin.com\/company\/fil-katia\/","https:\/\/www.pinterest.com\/KatiaYarns\/","https:\/\/www.youtube.com\/c\/KatiaYarnsFabrics\/videos","https:\/\/www.tiktok.com\/@katiacrafts","https:\/\/www.instagram.com\/katiafabrics"]},{"@type":"Person","@id":"https:\/\/www.katia.com\/blog\/es\/#\/schema\/person\/7f7e1104097c12cdcd6f14538e89f243","name":"Marisa Guerrero | Katia Team","description":"At Katia, we've been creating yarns for crafts for over 70 years. Each season, we develop new high-quality yarns under the Katia, WOW!, Lanas Stop, and Concept by Katia brands. Inspired by our wide and varied collection of yarns, we also publish knitting and crochet pattern magazines for garments and accessories for Women, Men, Kids, Babies, and Home.","url":"https:\/\/www.katia.com\/blog\/es\/author\/nuriacastello\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.katia.com\/blog\/wp-content\/uploads\/2023\/05\/knit-es-tejer-atlantico-shawl-pattern-2-3.jpg?fit=924%2C690&ssl=1","jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/peUVQy-kc9","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.katia.com\/blog\/es\/wp-json\/wp\/v2\/posts\/77633"}],"collection":[{"href":"https:\/\/www.katia.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.katia.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.katia.com\/blog\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.katia.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=77633"}],"version-history":[{"count":0,"href":"https:\/\/www.katia.com\/blog\/es\/wp-json\/wp\/v2\/posts\/77633\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.katia.com\/blog\/es\/wp-json\/wp\/v2\/media\/138359"}],"wp:attachment":[{"href":"https:\/\/www.katia.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=77633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.katia.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=77633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.katia.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=77633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}